{"id":2629,"date":"2019-08-30T16:50:34","date_gmt":"2019-08-30T20:50:34","guid":{"rendered":"https:\/\/outlift.com\/deadlift-for-muscle\/"},"modified":"2021-02-20T17:47:24","modified_gmt":"2021-02-20T22:47:24","slug":"peso-muerto-guia-para-ganar-musculo","status":"publish","type":"post","link":"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/","title":{"rendered":"El Peso Muerto (Gu\u00eda para Tama\u00f1o &#038; Est\u00e9tica)"},"content":{"rendered":"\n<p>El peso muerto fortalece a nuestro cuerpo desde los dedos de las manos hasta los dedos de los pies, estimulando a una gran cantidad de m\u00fasculos del cuerpo, desde los antebrazos hasta las pantorillas. De hecho, es tan buen indicador de la fuerza general que es el \u00fanico levantamiento fundamental tanto en el levantamiento de potencia (<em>powerlifting<\/em>) como en el entrenamiento de <em>strongman<\/em>.<\/p>\n\n\n\n<p>Sin embargo, cuando se trata del tama\u00f1o muscular y de est\u00e9tica, el peso muerto es un poco controversial. La mayor\u00eda de personas que entrenan de forma casual no lo hacen, y muchos fisicoculturistas profesionales tambi\u00e9n lo dejan de lado. Y la raz\u00f3n es simple: el peso muerto es dif\u00edcil de hacer, es dif\u00edcil recuperarse despu\u00e9s de hacerlo, y genera preocupaci\u00f3n frente a la posibilidad de tener una lesi\u00f3n de espalda.<\/p>\n\n\n\n<p>Adem\u00e1s, la mayor\u00eda de levantadores de potencia y <em>strongmen<\/em> hacen el peso muerto con la meta de desarrollar su fuerza para una \u00fanica repetici\u00f3n de esfuerzo m\u00e1ximo. Es un estilo de entrenamiento diferente, dise\u00f1ado para obtener un resultado diferente.<\/p>\n\n\n\n<p>Si tu meta es construir un cuerpo con m\u00e1s fuerza, m\u00fasculo y con mejor apariencia, lo ideal es hacer el peso muerto de una forma un poco distinta.<\/p>\n\n\n\n<!--more La Gu\u00eda del Peso mUERTO-->\n\n\n<div class=\"wp-block-ub-table-of-contents-block ub_table-of-contents\" id=\"ub_table-of-contents-58df45d2-1485-4a1b-b8a5-6b5baf890e53\" data-linktodivider=\"false\" data-showtext=\"show\" data-hidetext=\"hide\" data-scrolltype=\"auto\" data-enablesmoothscroll=\"true\" data-initiallyhideonmobile=\"false\" data-initiallyshow=\"true\"><div class=\"ub_table-of-contents-header-container\" style=\"\">\n\t\t\t<div class=\"ub_table-of-contents-header\" style=\"text-align: left; \">\n\t\t\t\t<div class=\"ub_table-of-contents-title\" style=\"\">Tabla de Contenido<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div><div class=\"ub_table-of-contents-extra-container\" style=\"\">\n\t\t\t<div class=\"ub_table-of-contents-container ub_table-of-contents-1-column \">\n\t\t\t\t<ol style=\"\"><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#0-el-peso-muerto-para-tama%C3%B1o-fuerza-amp-est%C3%A9tica\" style=\"\">El Peso Muerto para Tama\u00f1o, Fuerza &amp; Est\u00e9tica<\/a><ol><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#1-el-peso-muerto-para-ganar-fuerza-general\" style=\"\">El Peso Muerto para Ganar Fuerza General<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#2-el-peso-muerto-para-ganar-masa-muscular\" style=\"\">El Peso Muerto para Ganar Masa Muscular<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#3-el-peso-muerto-para-la-est%C3%A9tica\" style=\"\">El Peso Muerto para la Est\u00e9tica<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#4-el-peso-muerto-y-la-fatiga\" style=\"\">El Peso Muerto y la Fatiga<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#5-el-peso-muerto-y-la-columna\" style=\"\">El Peso Muerto y la Columna<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#6-el-peso-muerto-y-el-cuello\" style=\"\">El Peso Muerto y el Cuello<\/a><\/li><\/ol><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#7-el-peso-muerto-convencional\" style=\"\">El Peso Muerto Convencional<\/a><ol><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#8-por-qu%C3%A9-el-peso-muerto-convencional-es-el-mejor-para-ganar-m%C3%BAsculo\" style=\"\">Por qu\u00e9 el Peso Muerto Convencional es el Mejor para Ganar M\u00fasculo<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#9-c%C3%B3mo-hacer-el-peso-muerto-convencional\" style=\"\">C\u00f3mo Hacer el Peso Muerto Convencional<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#10-optimizando-el-rango-de-movimiento\" style=\"\">Optimizando el Rango de Movimiento<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#11-diagnosticando-eslabones-d%C3%A9biles\" style=\"\">Diagnosticando Eslabones D\u00e9biles<\/a><\/li><\/ol><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#17-alternativas-al-peso-muerto-convencional\" style=\"\">Alternativas al Peso Muerto Convencional<\/a><ol><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#18-el-peso-muerto-sumo\" style=\"\">El Peso Muerto Sumo<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#19-el-peso-muerto-con-barra-hexagonal\" style=\"\">El Peso Muerto con Barra Hexagonal<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#20-el-peso-muerto-rumano\" style=\"\">El Peso Muerto Rumano<\/a><\/li><\/ol><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#21-alternativas-con-el-peso-corporal\" style=\"\">Alternativas con el Peso Corporal<\/a><ol><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#22-el-peso-muerto-con-peso-corporal-con-toalla\" style=\"\">El Peso Muerto con Peso Corporal con Toalla<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#23-el-empuje-de-cadera\" style=\"\">El Empuje de Cadera<\/a><\/li><\/ol><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#24-levantamientos-de-asistencia\" style=\"\">Levantamientos de Asistencia<\/a><ol><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#25-el-peso-muerto-rumano-a-una-pierna\" style=\"\">El Peso Muerto Rumano a una Pierna<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#26-el-peso-muerto-con-agarre-ancho\" style=\"\">El Peso Muerto con Agarre Ancho<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#27-la-sentadilla-frontal-sentadilla-zercher-\" style=\"\">La Sentadilla Frontal \/ Sentadilla Zercher<\/a><\/li><\/ol><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#28-levantamientos-accesorios\" style=\"\">Levantamientos Accesorios<\/a><ol><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#29-remos-con-barra\" style=\"\">Remos con Barra<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#30-puentes-de-gl%C3%BAteos-empujes-de-cadera\" style=\"\">Puentes de Gl\u00fateos \/ Empujes de Cadera<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#31-elevaciones-de-espalda-hiperextensiones-invertidas\" style=\"\">Elevaciones de Espalda\/ Hiperextensiones Invertidas<\/a><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#32-buenos-d%C3%ADas-good-mornings-\" style=\"\">Buenos D\u00edas (Good Mornings )<\/a><\/li><\/ol><\/li><li style=\"\"><a href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#33-puntos-clave\" style=\"\">Puntos Clave<\/a><\/li><\/ol>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"0-el-peso-muerto-para-tama%C3%B1o-fuerza-amp-est%C3%A9tica\">El Peso Muerto para Tama\u00f1o, Fuerza &amp; Est\u00e9tica<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"730\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/conventional-deadlift-technique.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un peso muerto convencional.\" class=\"wp-image-1400\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/conventional-deadlift-technique.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/conventional-deadlift-technique-300x174.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/conventional-deadlift-technique-1024x593.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/conventional-deadlift-technique-768x445.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"1-el-peso-muerto-para-ganar-fuerza-general\">El Peso Muerto para Ganar Fuerza General<\/h3>\n\n\n\n<p><strong>De todos los levantamientos, el peso muerto tiene la mayor transferencia a la fuerza general.<\/strong> Hacer el peso muerto no s\u00f3lo nos ayudar\u00e1 a levantar cosas pesadas, sino que tambi\u00e9n fortalecer\u00e1 a nuestra columna, tendones y huesos, por lo cual tambi\u00e9n causa que levantar esas cosas pesadas sea m\u00e1s seguro.<\/p>\n\n\n\n<p>Por otra parte, algunas personas piensan que el riesgo de lesionarse es muy alto. Si nuestra meta es desarrollar fuerza general duradera, \u00bfpor qu\u00e9 deber\u00edamos arriesgarnos cargando a la columna con tanto peso?, \u00bfpor qu\u00e9 deber\u00edamos arriesgarnos y provocar una hernia? <\/p>\n\n\n\n<p>Hay un problema con este razonamiento. El levantamiento de pesas est\u00e1 dise\u00f1ado para fortalecernos, no para quebrarnos. S\u00ed, implica imponer un estr\u00e9s sobre el cuerpo, pero esa es la forma en la cual lo llevamos a adaptarse. S\u00ed lo hacemos adecuadamente, podemos minimizar los riesgos al tiempo que maximizamos los beneficios.<\/p>\n\n\n\n<p>El peso muerto, ejecutado correctamente, fortalecer\u00e1 a nuestra columna y reducir\u00e1 el riesgo de tener una lesi\u00f3n, especialmente con el paso de los a\u00f1os.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"2-el-peso-muerto-para-ganar-masa-muscular\">El Peso Muerto para Ganar Masa Muscular<\/h3>\n\n\n\n<p><strong>Al hablar del rol que tiene para ganar masa muscular, el peso muerto es controversial<\/strong>, y a primera vista, esto puede ser dif\u00edcil de entender. El peso muerto es excelente para ganar tama\u00f1o muscular en los isquiosurales, caderas, antebrazos y la espalda:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"1207\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-trabajados-peso-muerto.jpg\" alt=\"Diagrama de los m\u00fasculos trabajados `por el peso muerto.\" class=\"wp-image-6376\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-trabajados-peso-muerto.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-trabajados-peso-muerto-300x287.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-trabajados-peso-muerto-1024x981.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-trabajados-peso-muerto-768x736.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><figcaption>El peso muerto es bueno para aumentar el tama\u00f1o de los m\u00fasculos superficiales de la espalda.<\/figcaption><\/figure>\n\n\n\n<p>Pero, lo m\u00e1s impresionante del peso muerto es su habilidad de desarrollar los m\u00fasculos m\u00e1s profundos de la espalda\u2014los erectores de la columna y el m\u00fasculos transverso del abdomen:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"1207\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-profundos-trabajados-peso-muerto.jpg\" alt=\"Diagrama que muestra que el peso muerto tambi\u00e9n trabaja a los erectores de la columna y al m\u00fasculo transverso del abdomen.\" class=\"wp-image-6379\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-profundos-trabajados-peso-muerto.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-profundos-trabajados-peso-muerto-300x287.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-profundos-trabajados-peso-muerto-1024x981.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-profundos-trabajados-peso-muerto-768x736.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><figcaption>El peso muerto es a\u00fan mejor para los m\u00fasculos m\u00e1s profundos de la espalda.<\/figcaption><\/figure>\n\n\n\n<p>Y ten en cuenta que estos m\u00fasculos no s\u00f3lo est\u00e1n meramente activos durante un peso muerto, sino que tambi\u00e9n son posibles factores limitantes, por lo cual  van a ser desafiados lo suficiente para estimular su crecimiento.<\/p>\n\n\n\n<p>En t\u00e9rminos de la cantidad de crecimiento muscular global estimulado, s\u00f3lo las sentadillas se comparan.<\/p>\n\n\n\n<p>Sin embargo, si quieres hacer el peso muerto con la meta de ganar masa muscular, hay algunas consideraciones que debemos abordar:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Ajustar el tempo. <\/strong>Al hacer un peso muerto pesado, la mayor\u00eda de personas levantan la barra y luego la sueltan, eliminando la parte exc\u00e9ntrica del levantamiento. Lo que se piensa es que al hacerlo, ahorramos energ\u00eda y reducimos el riesgo de lesi\u00f3n. El problema es que vamos a ganar m\u00e1s m\u00fasculo si hacemos levantamientos que tengan tanto una porci\u00f3n conc\u00e9ntrica como una exc\u00e9ntrica. Esto significa que, si tu meta es ganar m\u00fasculo, deber\u00edas bajar el peso de forma controlada. Si mantienes una posici\u00f3n adecuada, no hay ninguna raz\u00f3n por la cual el riesgo de lesi\u00f3n aumente. Si no <em>puedes<\/em> mantener una posici\u00f3n adecuada al bajar la barra, deber\u00edas utilizar menos peso, de tal forma que s\u00ed puedas.<\/li><li><strong>La posici\u00f3n inicial y las caderas.<\/strong> La posici\u00f3n inicial de un peso muerto est\u00e1 determinada por el tama\u00f1o de los discos que utilices. Casi siempre, estos son discos de 45 libras est\u00e1ndares. El problema es que la movilidad de tus caderas podr\u00eda no coincidir con esta profundidad. Vamos a hablar de esto m\u00e1s adelante en la secci\u00f3n de rango de movimiento.<\/li><li><strong>El rango de movimiento. <\/strong>Diferentes variaciones del peso muerto utilizan diferentes rangos de movimiento. El peso muerto con barra hexagonal y el peso muerto sumo tienen un menor rango de movimiento, lo cual tiende a causar que sean peores para ganar masa muscular. El peso muerto convencional tiene un mayor rango de movimiento, lo cual hace que sea mejor para ganar m\u00fasculo (pero tambi\u00e9n implica que genera m\u00e1s fatiga).<\/li><li><strong>Alinear el factor limitante con tus metas. <\/strong>Dependiendo de la variaci\u00f3n de peso muerto que hagas, vas a fallar por diferentes razones. Si tu espalda tira la toalla primero, el peso muerto va a trabajar principalmente a la espalda (lo cual es com\u00fan con el peso muerto convencional). Si tus caderas se agotan primero, el peso muerto va a estimular principalmente a las caderas (lo cual es com\u00fan con el peso muerto sumo). Puedes escoger la variaci\u00f3n de peso muerto basado en los grupos musculares que quieres estimular en mayor medida. Para ganar tama\u00f1o muscular en general, recomendamos el peso muerto convencional.<\/li><li><strong>Fuerza de agarre. <\/strong>Muchas personas fallan el peso muerto debido a una falta de fuerza de agarre, especialmente cuando no empiezan a hacerlo por primera vez. Este problema debe solucionarse por medio de un agarre mixto, un agarre (de) gancho, utilizando tiza para las manos, correas, o accesorios que permitan mejorar la fuerza de agarre. De lo contrario, el peso muerto simplemente ser\u00e1 un ejercicio para los antebrazos.<\/li><li><strong>Fatiga.<\/strong> El peso muerto genera mucha fatiga, especialmente si est\u00e1s limitado por los erectores de la columna y\/o por tu fuerza de agarre. A diferencia de los dem\u00e1s levantamientos compuestos grandes, usualmente es mejor hacer el peso muerto con un volumen y frecuencia bastante bajos, pero con m\u00e1s trabajo de asistencia y accesorio.<\/li><\/ul>\n\n\n\n<p>Todo esto quiere decir que, aunque com\u00fanmente se programa con el fin de mejorar la fuerza general, con algunas modificaciones el peso muerto tambi\u00e9n puede ser un excelente ejercicio para ganar m\u00fasculo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"3-el-peso-muerto-para-la-est%C3%A9tica\">El Peso Muerto para la Est\u00e9tica<\/h3>\n\n\n\n<p><strong>En cuanto a su impacto para la est\u00e9tica, el peso muerto est\u00e1 incre\u00edblemente subestimado<\/strong><b>. <\/b>El peso muerto desarrolla los m\u00fasculos del <em>\u00abyugo<\/em>\u00ab, los cuales nos hacen ver m\u00e1s fuertes y dominantes: los trapecios, los antebrazos, los erectores de la columna y los gl\u00fateos.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Para los hombres con cuerpos naturalmente m\u00e1s delgados<\/strong>, aumentar el tama\u00f1o de nuestros erectores de la columna es especialmente importante. As\u00ed como la sentadilla frontal, el peso muerto va a ensanchar nuestra espalda.<\/li><li><strong>Para los hombres con cuellos m\u00e1s largos y delgados<\/strong>, nada va a mejorar tu apariencia como construir trapecios grandes sobre los cuales descanse tu cuello.<\/li><li><strong>Para hombres con brazos m\u00e1s largos y delgados<\/strong>, nada va a ser que se vean m\u00e1s gruesos como un par de antebrazos musculares, junto a un par de manos s\u00f3lidas y fuertes.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"805\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/posterior-chain-bulking-exercise-thicker-torso.jpg\" alt=\"Ilustraci\u00f3n del antes y despu\u00e9s de un hombre despu\u00e9s de aumentar el tama\u00f1o de su torso.\" class=\"wp-image-2449\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/posterior-chain-bulking-exercise-thicker-torso.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/posterior-chain-bulking-exercise-thicker-torso-300x192.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/posterior-chain-bulking-exercise-thicker-torso-1024x654.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/posterior-chain-bulking-exercise-thicker-torso-768x491.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><figcaption>El peso muerto tiene un gran impacto sobre nuestra apariencia.<\/figcaption><\/figure>\n\n\n\n<p>Si est\u00e1s de acuerdo con la idea de que los hombres que se ven m\u00e1s formidables son m\u00e1s atractivos, el peso muerto es una gran herramienta para mejorar tu est\u00e9tica.<\/p>\n\n\n\n<p>S\u00ed, el peso muerto es dif\u00edcil. Pero si queremos mejorar nuestra apariencia, no hay nada mejorar que tener un cuerpo que sea vea capaz de hacer cosas dif\u00edciles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"4-el-peso-muerto-y-la-fatiga\">El Peso Muerto y la Fatiga<\/h3>\n\n\n\n<p>El peso muerto es famoso por ser dif\u00edcil. Al hacerlo, involucramos a casi todos los m\u00fasculos del cuerpo, levantamos una gran cantidad de peso, y ese eso est\u00e1 soportado por nuestra columna. <\/p>\n\n\n\n<p>Pero, esto no suena tan mal. Despu\u00e9s de todo, las sentadillas tambi\u00e9n son dif\u00edciles. De hecho, <em>todos<\/em> <a href=\"https:\/\/outlift.com\/es\/cinco-grandes-levantamientos\/\">los mejores levantamientos para ganar m\u00fasculo<\/a> son dif\u00edciles. Y a\u00fan as\u00ed, son estos levantamientos los que nos dan los mejores resultados. Una sola serie pesada del peso muerto puede reemplazar a una sesi\u00f3n de entrenamiento mediocre entera. Sin embargo, el peso muerto es <em>desproporcionalmente <\/em>agotador.<\/p>\n\n\n\n<p>Para poner esto en perspectiva, comparemos al peso muerto con la sentadilla, en t\u00e9rminos de su habilidad para generar fatiga. Ambos involucran a una gran cantidad de masa muscular bajo carga pesada, que debe ser soportada por nuestra columna. Son similares en muchos aspectos.<\/p>\n\n\n\n<p>Pero, tan pronto como observamos la forma en las que son programados, es posible identificar que hay algo raro. Programas como <em>Starting Strength<\/em> recomiendan iniciar cada sesi\u00f3n con tres series de sentadillas pesadas. <em>StrongLifts<\/em> recomienda empezar con <em>cinco<\/em> series pesadas de sentadillas. Incluso tal vez has escuchado de programas que recomiendan hacer sentadillas todos los d\u00edas (como <em>Smolov<\/em>). En cualquier caso, son bastantes sentadillas. Pero las personas pueden hacerlo sin problema. Esto se debe a que las sentadillas no generan <em>tanta<\/em> fatiga.<\/p>\n\n\n\n<p>Ahora hablemos del peso muerto. Tanto <em>Starting Strength<\/em> como <em>StrongLifts<\/em> recomiendan hacer el peso muerto 1-2 veces por semana, dej\u00e1ndolos para el final de la sesi\u00f3n, y haciendo una sola serie. Eso quiere decir que en <em>Starting Strength<\/em> se hacen 6 veces la cantidad de sentadillas que de peso muerto. En StrongLifts, se hacen 10 veces m\u00e1s sentadillas. Y no hay ni un solo programa (razonable) que recomiende hacer el peso muerto todos los d\u00edas. Esto se debe a que el peso muerto es mucho m\u00e1s demandante para el cuerpo que las sentadillas.<\/p>\n\n\n\n<p><strong>Pero, \u00bfpor qu\u00e9?<\/strong> Hay algunas teor\u00edas al respecto. Principalmente se debe a que el peso muerto impone una gran carga sobre la columna\u2014carga axial\u2014con nuestro torso en una posici\u00f3n m\u00e1s horizontal, lo cual demanda bastante de los erectores de la columna. Cuando los erectores de la columna se agotan, nosotros nos agotamos.<\/p>\n\n\n\n<p>Hacer el peso muerto puede dejar destrozados a los levantadores principiantes por d\u00edas. Sentarse derecho en una silla puede ser dif\u00edcil, y ni hablar de todo lo dem\u00e1s.<\/p>\n\n\n\n<p>Tambi\u00e9n est\u00e1 el hecho de que sostener tanto peso con tanta fuerza puede desgarrar un poco a nuestras manos. Cuando nuestras manos est\u00e1n as\u00ed, no queremos sostener nada.<\/p>\n\n\n\n<p>Si s\u00f3lo queremos ganar masa muscular, \u00bfpor qu\u00e9 deber\u00edamos someternos a algo tan dif\u00edcil? \u00bfNo ser\u00eda mejor invertir nuestra energ\u00eda haciendo otros levantamientos? La respuesta es simple: para estimular tanto crecimiento muscular como el peso muerto, ser\u00eda necesario hacer una docena de levantamientos diferentes, incluyendo algunos que cargan a nuestra columna de forma considerable. Acumular\u00edamos la misma cantidad de fatiga, pero nos tomar\u00eda una sesi\u00f3n entera en vez de s\u00f3lo algunas series.<\/p>\n\n\n\n<p>Pero, alguien podr\u00eda argumentar, a\u00fan si decidimos hacer el peso muerto, \u00bfno ser\u00eda escoger una variaci\u00f3n m\u00e1s f\u00e1cil, como el peso muerto rumano? A fin de cuentas, es el mismo patr\u00f3n de movimiento, pero genera menos fatiga. Podr\u00edamos estimular a los isquiosurales similarmente, pero imponiendo menos estr\u00e9s sobre nuestra espalda.<\/p>\n\n\n\n<p>La raz\u00f3n por la que estamos en desacuerdo con esa idea es que, aquello que hace que el peso muerto genere tanta fatiga es precisamente lo que lo hace tan excelente.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Capacidad de trabajo. <\/strong>Acostumbrarnos a hacer levantamientos m\u00e1s demandantes aumentar\u00e1 nuestra capacidad de trabajo, lo cual nos permitir\u00e1 soportar un volumen m\u00e1s alto de levantamientos m\u00e1s dif\u00edciles. Esto es especialmente cierto si ponemos un \u00e9nfasis adicional en aumentar el tama\u00f1o de los erectores de la columna, con lo cual nuestra columna tendr\u00e1 un poco de soporte adicional.<\/li><li><strong>Una columna m\u00e1s fuerte.<\/strong> La raz\u00f3n por la cual el peso muerto es tan fatigante se debe a todo el estr\u00e9s impuesto sobre la columna. Pero ese estr\u00e9s fortalecer\u00e1 a nuestra columna. Esto har\u00e1 que los dem\u00e1s levantamientos sean m\u00e1s f\u00e1ciles.<\/li><li><strong>Huesos m\u00e1s densos. <\/strong>Aunque es m\u00e1s que nada especulaci\u00f3n, parece ser que hay una relaci\u00f3n entre la masa \u00f3sea y el potencial gen\u00e9tico para ganar m\u00fasculo. En primer lugar, la investigaci\u00f3n de Casey Butts, PhD, encontr\u00f3 que los hombres con m\u00e1s masa \u00f3sea pueden ganar m\u00e1s m\u00fasculo. En segundo lugar, investigadores especializados en huesos han identificado que cuando las personas pierden densidad \u00f3sea, su masa muscular tambi\u00e9n tiende a disminuir. Yo pienso que incluir en nuestras rutinas algunos levantamientos que sea buenos para mejorar la densidad de nuestros huesos, no s\u00f3lo es saludable, sino que tambi\u00e9n es una buen idea en t\u00e9rminos de la ganancia muscular a largo plazo.<\/li><li><strong>Eficiencia de <em>tiempo<\/em>.<\/strong> Es cierto que el peso muerto genera mucha fatiga por unidad de crecimiento muscular estimulado, pero si tambi\u00e9n consideramos que el peso muerto estimula una tremenda cantidad de crecimiento muscular por unidad de tiempo, el balance comienza a ser positivo. Dedicar quince minutos a la semana para hacer algunas series de peso muerto puede generar una cantidad desproporcional de fatiga, pero tambi\u00e9n produce una cantidad de crecimiento muscular global desproporcional.<\/li><\/ul>\n\n\n\n<p>Adem\u00e1s, la mayor\u00eda de programas bien dise\u00f1ados toman en cuenta que el peso muerto genera bastante fatiga. Por esto, usualmente veras que el peso muerto est\u00e1 programado con un menor volumen y frecuencia.<\/p>\n\n\n\n<p>Podemos obtener el mayor beneficio, minimizando las desventajas, haciendo s\u00f3lo algunas series de peso muerto a la semana, combin\u00e1ndolas con algunos levantamientos de asistencia y accesorios para obtener el volumen y la frecuencia ideal para ganar m\u00fasculo y fuerza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"5-el-peso-muerto-y-la-columna\">El Peso Muerto y la Columna<\/h3>\n\n\n\n<p>Es posible que hayas escuchado que el peso muerto es peligroso, y ciertamente puede serlo. Hay un riesgo inherente a cada levantamiento. Lo que debemos hacer es minimizar esos riesgos al tiempo que obtenemos la mayor cantidad de beneficios que podamos.<\/p>\n\n\n\n<p>Hay dos formas populares de abordar el levantamiento de pesas, y ambas son opuestas, en especial cuando se trata del peso muerto. Algunas personas consideran que son invencibles, y hacen cosas sin pensarlo bien, sin importar cu\u00e1l sea el riesgo. Otros, consideran que son fragiles y evitan hacer cualquier cosa que pueda lastimarlos.<\/p>\n\n\n\n<p>Aquellos que comienzan a levantar pesas sin cuidado usualmente van a lastimarse, y el peso muerto puede ser particularmente problem\u00e1tico en este sentido. Tener la espalda torcida durante el levantamiento hace que este sea m\u00e1s f\u00e1cil para las caderas, debido a que acorta <a href=\"https:\/\/outlift.com\/es\/brazos-de-momento-y-crecimiento-muscular\/\">el brazo de momento<\/a>:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"880\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazo-de-momento-peso-muerto-espalda-curvada.jpg\" alt=\"Ilustraci\u00f3n del efecto que doblar la espalda tiene sobre la ejecuci\u00f3n del peso muerto.\" class=\"wp-image-6381\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazo-de-momento-peso-muerto-espalda-curvada.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazo-de-momento-peso-muerto-espalda-curvada-300x210.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazo-de-momento-peso-muerto-espalda-curvada-1024x715.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazo-de-momento-peso-muerto-espalda-curvada-768x536.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><figcaption>Hacer el peso muerto con una columna neutral requiere de m\u00e1s fuerza de cadera.<\/figcaption><\/figure>\n\n\n\n<p>Esto permite sostener el peso con la columna y levantar con la fuerza bruta de las caderas. Esto no es bueno. Nuestra columna es fuerte, y es posible que logre mantener esa posici\u00f3n durante un buen tiempo, pero hay un l\u00edmite de estupidez que puede aguantar. No siempre pasa, y no siempre es inmediato, pero hacer el peso muerto de esta forma usualmente lleva a una lesi\u00f3n.<\/p>\n\n\n\n<p>En el otro extremo, las personas cuidadosas escuchan acerca de estas lesiones y pierden la motivaci\u00f3n. Cualquier sensaci\u00f3n en la parte inferior de la espalda el d\u00eda despu\u00e9s de entrenar las preocupa. El peso muerto, en su mente, se convierte en una forma de atentar contra la integridad de su fr\u00e1gil columna.<\/p>\n\n\n\n<p>Pero, a\u00fan si crees que tu columna es fr\u00e1gil, todav\u00eda tienes un par de opciones. La primera ser\u00eda estimular el crecimiento alrededor de la columna, pero nunca estres\u00e1ndola directamente, con lo cual la columna se volver\u00eda gradualmente m\u00e1s d\u00e9bil. La otra opci\u00f3n ser\u00eda fortalecer a la columna al punto de que ya no sea fr\u00e1gil.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Los huesos de una persona o animal saludable se adaptar\u00e1n a las cargas que le sean impuestas.<\/p><cite><em>Ley de Wolff&#8217;s<\/em>, descubierta por Julius Wolff, PhD<\/cite><\/blockquote>\n\n\n\n<p>Lo interesante de los erectores de la columna es que, a pesar de que cubren a toda la columna, est\u00e1n conformados por muchos m\u00fasculos peque\u00f1os que s\u00f3lo cubren a un par de vertebras.  Esto significa que tu espalda puede ser fuerte en algunos lugares y d\u00e9bil en otros. Puedes tener una espalda superior fuerte y una espalda inferior d\u00e9bil, y vice versa. Lo bueno del peso muerto convencional es que fortalece a toda la columna, de abajo hasta arriba.<\/p>\n\n\n\n<p>La sobrecarga progresiva es un proceso gradual. Un par de libras un d\u00eda, una repetici\u00f3n adicional en otro. Si estresas un poco a un disco hoy, tendr\u00e1s un disco un poco m\u00e1s fuerte ma\u00f1ana. Es posible que empecemos levantando una cantidad modesta de peso con nuestra espalda fr\u00e1gil, pero nuestra columna se adaptar\u00e1 como nuestros m\u00fasculos, fortaleci\u00e9ndose a medida que nos volvamos m\u00e1s fuertes (<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/26409630\" target=\"_blank\" rel=\"noreferrer noopener\">estudio<\/a>).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>El entrenamiento intensivo aumentar\u00e1 el contenido mineral \u00f3seo al punto que la columna puede tolerar cargas extraordinarias.<\/p><cite><a aria-label=\"Spinal loading research (opens in a new tab)\" href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/3589805\" target=\"_blank\" rel=\"noreferrer noopener\">Investigaci\u00f3n de carga sobre la columna<\/a> por Granhed et al<\/cite><\/blockquote>\n\n\n\n<p>Pero, sigue siendo una buena idea ser cuidadosos. Por ejemplo, nosotros recomendamos una descarga de forma peri\u00f3dica, en donde le demos al cuerpo la posibilidad de recuperarse completamente de cualquier da\u00f1o menor que hayamos acumulado. Cada cierto n\u00famero de semanas, realiza un par de sesiones m\u00e1s f\u00e1ciles. Cada cierto n\u00famero de meses, t\u00f3mate una semana de descanso. Cada cierto n\u00famero de a\u00f1os, t\u00f3mate un mes de descanso.<\/p>\n\n\n\n<p>No es necesario dejar de entrenar completamente, simplemente es un descanso de la carga pesada sobre la columna. Por ejemplo, podr\u00edas dedicar algunas semanas cada a\u00f1o a hacer el peso muerto rumano a una pierna, en vez del peso muerto convencional.<\/p>\n\n\n\n<p>Pero, primero lo primero. Para minimizar el riesgo de lesi\u00f3n al tiempo que obtenemos todos los beneficios, tenemos que hacer el peso muerto con una buena t\u00e9cnica. Diferentes personas tienen diferentes ideas de lo que esto significa.<\/p>\n\n\n\n<p>Hay dos formas populares de hacer el peso muerto (adecuadamente):<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Estilo Strongman: <\/strong>el objetivo de los <em>strongmen <\/em>es construir una espalda que sea fuerte a\u00fan en posiciones que no son seguras, por lo cual hacen el peso muerto con mucho peso e intensidad. La barra usualmente inicia en una posici\u00f3n m\u00e1s alta, lo cual permite utilizar m\u00e1s peso. Ellos tambi\u00e9n utilizan correas que, nuevamente, permiten utilizar m\u00e1s peso sin que el agarre sea un problema. Dentro de las reglas de competici\u00f3n est\u00e1 permitido el <em>hitching<\/em> que consiste en descansar la barra sobre las rodillas y luego arrastrarla por los muslos hacia arriba. Tambi\u00e9n vas a ver a los <em>strongmen<\/em> levantando la barra con la espalda curvada en varios levantamientos, incluyendo el peso muerto, de forma intencional.<\/li><li><strong>Estilo <em>Powerlifter<\/em>:<\/strong> el levantador de potencia o <em>powerlifter<\/em> tiene como objetivo hacer el peso muerto con una t\u00e9cnica absolutamente perfecta. Siguen haci\u00e9ndolo con bastante peso, pero la barra empieza m\u00e1s abajo, no se permite el uso de las correas y el <em>hitching<\/em> est\u00e1 prohibido. Esto implica utilizar menos peso, un mayor rango de movimiento y una cantidad de estr\u00e9s sobre la columna m\u00e1s estable. En el levantamiento de potencia todos los levantamientos se realizan con una columna en posici\u00f3n neutral, especialmente el peso muerto.<\/li><\/ul>\n\n\n\n<p>La investigaci\u00f3n del Dr. Stuart McGill encontr\u00f3 que hacer el peso muerto con una espalda curvada pone alrededor de <em>950%<\/em> del estr\u00e9s de cizallamiento sobre la columna, en comparaci\u00f3n con una posici\u00f3n neutral. Por tanto, no es ninguna sorpresa que los <em>strongmen <\/em>tengan casi el doble de la tasa de lesiones que los levantadores de potencia (<a href=\"https:\/\/www.strengthandconditioningresearch.com\/2014\/07\/08\/injury-strength-sports\/\" target=\"_blank\" rel=\"noreferrer noopener\">fuente<\/a>).<\/p>\n\n\n\n<p>Para la mayor\u00eda de nosotros, lo mejor es hacer el peso muerto como los levantadores de potencia, manteniendo nuestra columna en el rango neutral. Si lo hacemos, podemos contar con una menor probabilidad de lesionarnos que las personas que trotan, los jugadores de f\u00fatbol y los triatletas.<\/p>\n\n\n\n<p>Pero, no s\u00f3lo queremos estar seguros, tambi\u00e9n queremos ganar m\u00fasculo y fuerza. Y m\u00e1s all\u00e1 de la etapa de principiante, mejorar implica que debemos salir de nuestra zona de comfort y luchar para a\u00f1adir peso a la barra.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"637\" src=\"https:\/\/outlift.com\/wp-content\/uploads\/2020\/04\/ilustracion-posicion-peso-muerto-estricta-vs-rango-neutral-1024x637.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un peso muerto con una posici\u00f3n de la columna neutral estricta y otro con una posici\u00f3n dentro del rango neutral.\" class=\"wp-image-1927\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2020\/04\/ilustracion-posicion-peso-muerto-estricta-vs-rango-neutral-1024x637.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2020\/04\/ilustracion-posicion-peso-muerto-estricta-vs-rango-neutral-300x187.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2020\/04\/ilustracion-posicion-peso-muerto-estricta-vs-rango-neutral-768x478.jpg 768w, https:\/\/outlift.com\/wp-content\/uploads\/2020\/04\/ilustracion-posicion-peso-muerto-estricta-vs-rango-neutral.jpg 1260w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Un peso muerto desafiante va a causar que nuestra espalda se flexione. Eso no es necesariamente malo.<\/figcaption><\/figure>\n\n\n\n<p>A medida que levantamos m\u00e1s peso y nos acercamos al m\u00e1ximo que podemos levantar o en las \u00faltimas repeticiones de una serie desafiante, nuestra t\u00e9cnica perfecta va a comenzar a tambalear. Si la fuerza de la espalda es nuestro factor limitante, es posible que los erectores de la columna se estiren un poco y nuestra espalda comience a flexionarse. Es normal.<\/p>\n\n\n\n<p>A medida que a\u00f1adamos peso a la barra, los erectores de la columna van a crecer juntos, y el estr\u00e9s sobre la espalda ser\u00e1 repartido entre diferentes vertebras de la columna, minimizando el estr\u00e9s sobre las articulaciones individuales.<\/p>\n\n\n\n<p>Lo importante es que la curva de la espalda debe ser modesta y sutil. Siempre y cuando la flexi\u00f3n sea de s\u00f3lo uno o dos grados en cada vertebra, seguimos dentro del \u00abrango\u00bb neutral, en el cual nuestras vertebras siguen m\u00e1s o menos en la mitad de su rango de movimiento. En esta posici\u00f3n un poco flexionada, el estr\u00e9s de cizallamiento deber\u00eda seguir siendo tolerable, y el riesgo de lesi\u00f3n deber\u00eda seguir siendo bajo.<\/p>\n\n\n\n<p><strong>El punto es que<\/strong> el peso muerto deber\u00eda hacerse con cuidado, para reducir nuestro riesgo de lesi\u00f3n. Pero tambi\u00e9n necesitamos hacerlo con un peso considerable, con intensidad, y con confianza, con el fin de provocar las adaptaciones beneficiales. Si podemos balancear el cuidado con la \u00abagresi\u00f3n\u00bb, con el tiempo, toda nuestra espalda\u2014incluidos los huesos y el tejido conectivo en la columna\u2014se volver\u00e1 m\u00e1s grande, fuerte, resiliente y robusta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"6-el-peso-muerto-y-el-cuello\">El Peso Muerto y el Cuello<\/h3>\n\n\n\n<p>De todos los levantamientos compuestos grandes, el peso muerto es el que probablemente vaya a estimular el crecimiento del cuello. De hecho, si consideramos a los trapecios superiores como parte del cuello, el peso muerto es un <em>excelente<\/em> ejercicio para el cuello; sin duda, el peso muerto va a aumentar el tama\u00f1o de tus trapecios.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"674\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-principales-del-cuello.jpg\" alt=\"Ilustraci\u00f3n de los m\u00fasculos del cuello, de los cuales el trapecio es trabajado por el peso muerto.\" class=\"wp-image-6207\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-principales-del-cuello.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-principales-del-cuello-300x160.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-principales-del-cuello-1024x548.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/musculos-principales-del-cuello-768x411.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><figcaption>El peso muerto es excelente para los trapecios, y posiblemente para el cuello.<\/figcaption><\/figure>\n\n\n\n<p>Sin embargo, si tambi\u00e9n quieres aumentar el tama\u00f1o del esternocleidomastoideo, que es el m\u00fasculo que hace que el cuello se vea m\u00e1s grueso, la relaci\u00f3n entre el peso muerto y el cuello se vuelve m\u00e1s d\u00e9bil.<\/p>\n\n\n\n<p>Si haces el peso muerto con una t\u00e9cnica cl\u00e1sica (ojos al frente, manteniendo la columna neutral de arriba hacia abajo), el peso muerto probablemente no va a estimular ning\u00fan crecimiento en el cuello. Esta t\u00e9cnica es considerada como la m\u00e1s segura, y es nuestra recomendaci\u00f3n predeterminada. (Pero no somos completamente r\u00edgidos al respecto.)<\/p>\n\n\n\n<p>Por otra parte, si tiendes a mirar hacia arriba al hacer el peso muerto, a medida que la barra jale los m\u00fasculos alrededor de la clav\u00edcula, es posible que tu esternocleidomastoideo se estire bajo carga, lo cual puede causar un poco de crecimiento. Sin embargo, esto mueve a la parte superior de la columna por fuera de la posici\u00f3n neutral, y aunque esta parte de la columna no va a soportar nada de la carga, algunos expertos de la columna afirman que es m\u00e1s peligroso. (Hay muy poca evidencia para afirmar si esto es cierto o no, pero depende de que tan cuidadosos queremos ser.)<\/p>\n\n\n\n<p>En todo caso, sin importar en qu\u00e9 posici\u00f3n est\u00e9 tu cuello al hacer el peso muerto, no hay ninguna garant\u00eda de que tu cuello va a crecer. Y a\u00fan si tu cuello s\u00ed crece, es poco probable que vaya a crecer muy r\u00e1pido o considerablemente.<\/p>\n\n\n\n<p>Como resultado, si quieres un cuello m\u00e1s grueso y fuerte, yo recomendar\u00eda hacer un poco de entrenamiento dedicado para el cuello. No vas a necesitar trabajo adicional para los trapecios superiores, pero probablemente quieras un poco de trabajo adicional para el esternocleidomastoideo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"7-el-peso-muerto-convencional\">El Peso Muerto Convencional<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"703\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/deadlift-conventional-illustration-1.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un peso muerto convencional.\" class=\"wp-image-1392\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/deadlift-conventional-illustration-1.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/deadlift-conventional-illustration-1-300x167.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/deadlift-conventional-illustration-1-1024x571.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/deadlift-conventional-illustration-1-768x428.jpg 768w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/deadlift-conventional-illustration-1-320x180.jpg 320w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"8-por-qu%C3%A9-el-peso-muerto-convencional-es-el-mejor-para-ganar-m%C3%BAsculo\">Por qu\u00e9 el Peso Muerto Convencional es el Mejor para Ganar M\u00fasculo<\/h3>\n\n\n\n<p><strong>El peso muerto convencional es la mejor variaci\u00f3n si est\u00e1s interesado en ganar tama\u00f1o muscular y fuerza general. <\/strong>Para entender por qu\u00e9, tenemos que mirar al \u00e1ngulo del torso y los brazos de momento:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"968\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/diferencia-brazo-momento-peso-muerto-convencional-vs-sumo.jpg\" alt=\"Ilustraci\u00f3n de la diferencia en el brazo de momento en un peso muerto convencional y un peso muerto sumo.\" class=\"wp-image-6199\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/diferencia-brazo-momento-peso-muerto-convencional-vs-sumo.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/diferencia-brazo-momento-peso-muerto-convencional-vs-sumo-300x230.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/diferencia-brazo-momento-peso-muerto-convencional-vs-sumo-1024x787.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/diferencia-brazo-momento-peso-muerto-convencional-vs-sumo-768x590.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<p>En un peso muerto convencional el torso est\u00e1 m\u00e1s horizontal y el brazo de momento para los m\u00fasculos de la espalda es m\u00e1s largo. Aunque, no es mucho mayor. La mayor\u00eda de estudios establecen que hay 8-10% m\u00e1s estimulaci\u00f3n de la espalda en el peso muerto convencional.<\/p>\n\n\n\n<p>Sin embargo, tambi\u00e9n es necesario levantar el peso a trav\u00e9s de una distancia mayor, con lo cual las caderas se mueven a lo largo de un <a href=\"https:\/\/outlift.com\/es\/rango-de-movimiento-crecimiento-muscular\/\">mayor rango de movimiento<\/a>, y los m\u00fasculos de la espalda deben estabilizar el peso por m\u00e1s tiempo. Como resultado, <a href=\"https:\/\/www.researchgate.net\/publication\/12406711_A_three-dimensional_biomechanical_analysis_of_sumo_and_conventional_style_deadlifts\" target=\"_blank\" rel=\"noreferrer noopener\">este estudio<\/a> encontr\u00f3 que el peso muerto convencional utiliza 25-40% m\u00e1s energ\u00eda que el peso muerto sumo.<\/p>\n\n\n\n<p>Esto no necesariamente significa que vamos a tener que utilizar menos peso con una posici\u00f3n convencional. Despu\u00e9s de todo, no fallamos una repetici\u00f3n debido a que nos cansamos al levantar el peso a trav\u00e9s de un rango de movimiento amplio; fallamos debido a que no somos suficientemente fuertes para levantar el peso m\u00e1s all\u00e1 del punto de mayor dificultad. En el punto de mayor dificultad, es poco probable que nuestra espalda sea el factor limitante. Por esto, la mayor\u00eda puede levantar una cantidad de peso similar en ambas posiciones, convencional o sumo.<\/p>\n\n\n\n<p>Sin embargo, aunque es posible utilizar una cantidad de peso similar, el peso muerto convencional probablemente se <em>sentir\u00e1<\/em> m\u00e1s dif\u00edcil. Esto se debe a que el peso muerto convencional tiene un rango de movimiento mayor y es m\u00e1s desafiante a lo largo de todo ese rango. Al comparar la posici\u00f3n convencional con la posici\u00f3n sumo, el estr\u00e9s <em>pico<\/em> por repetici\u00f3n es similar\u2014el punto de mayor dificultad es similarmente desafiante\u2014pero el estr\u00e9s <em>promedio<\/em> es mayor, lo cual resulta en m\u00e1s crecimiento muscular por repetici\u00f3n. but the <em>average<\/em> stress is greater, resulting in more muscle growth per rep. En suma, el peso muerto convencional tiene una mejor <a href=\"https:\/\/outlift.com\/es\/curvas-de-fuerza-para-ganar-musculo\/\">curva de fuerza<\/a>.<\/p>\n\n\n\n<p>El rango de movimiento m\u00e1s profundo en nuestras caderas tambi\u00e9n es bueno. Esto hace que el levantamiento desaf\u00ede a nuestras caderas en una posici\u00f3n estirada en la parte baja del movimiento, lo cual es ideal para el crecimiento muscular. Adem\u00e1s, a lo largo de la repetici\u00f3n, el \u00e9nfasis pasa de la parte inferior de la espalda (en la parte baja del movimiento) a la parte superior de la espalda (en la parte alta del movimiento). Por esto, tambi\u00e9n obtenemos un excelente desarrollo de la espalda.<\/p>\n\n\n\n<p>Todo esto quiere decir que, generalmente, el peso muerto convencional nos agota m\u00e1s y requiere de <a href=\"https:\/\/outlift.com\/es\/tiempos-de-descanso-para-crecimiento-muscular\/\">tiempos de descanso entre series<\/a> m\u00e1s largos. Sin embargo, tambi\u00e9n va a ser mejor para el crecimiento de las caderas y la espalda, para fortalecer a la columna y para mejorar nuestra condici\u00f3n f\u00edsica (para el levantamiento).<\/p>\n\n\n\n<p><strong>Como regla general, si est\u00e1s interesado en el tama\u00f1o muscular, fuerza general, condici\u00f3n f\u00edsica, y est\u00e9tica, escoge el peso muerto convencional.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"9-c%C3%B3mo-hacer-el-peso-muerto-convencional\">C\u00f3mo Hacer el Peso Muerto Convencional<\/h3>\n\n\n\n<p>El peso muerto es un levantamiento dif\u00edcil. Debes levantar una gran cantidad de peso y lo debes hacer de forma segura. Sin embargo, no es un levantamiento complicado. La mayor\u00eda de nosotros sabe c\u00f3mo levantar cosas del suelo de forma, y usualmente tenemos una buena intuici\u00f3n para hacerlo de forma segura.<\/p>\n\n\n\n<p>El peso muerto es, posiblemente, el levantamiento m\u00e1s simple y es muy f\u00e1cil de aprender; s\u00f3lo tienes que coger la barra, contraer los m\u00fasculos de la espalda (\u00abpecho arriba\u00bb), y jalar.<\/p>\n\n\n\n<p>Al hacer el peso muerto, tal vez quieras tener algunas indicaciones en mente:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Pecho arriba: <\/strong>mant\u00e9n el pecho arriba y los dorsales flexionados.<\/li><li><strong>Si\u00e9ntate atr\u00e1s:<\/strong> mueve las caderas hacia atr\u00e1s y siente c\u00f3mo aumenta la tensi\u00f3n en tus gl\u00fateos e isquiosurales. De ah\u00ed es de donde vendr\u00e1 tu potencia.<\/li><li><strong>Axilas r\u00edgida:<\/strong> antes de levantar el peso, aprieta tus axilas como si fueras al\u00e9rgico a las cosquillas.<\/li><li><strong>Jala la barra antes de levantarla.<\/strong> La idea es que, si hay 400 libras en la barra, pongas unos cientos de libras de presi\u00f3n sobre la barra antes de intentar levantarla. Con esto vas a quitar ese \u00abmargen\u00bb que existe entre la barra y los discos y los m\u00fasculos de la espalda podr\u00e1n activarse.<\/li><\/ul>\n\n\n\n<p>No obstante, probablemente no vas a tener que pensar demasiado. Para cuando seas un levantador intermedio el peso muerto deber\u00eda sentirse bastante intuitivo. Conf\u00eda en esa intuici\u00f3n. Tu espalda es fuerte, y tu eres fuerte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"10-optimizando-el-rango-de-movimiento\">Optimizando el Rango de Movimiento<\/h3>\n\n\n\n<p>Nuestros m\u00fasculos crecen en mejor medida cuando los desafiamos en una posici\u00f3n estirada, y esa es una de las razones por las cuales el peso muerto es tan bueno para ganar m\u00fasculo: la parte baja del levantamiento estira a los flexores de la cadera y tambi\u00e9n es la parte m\u00e1s dif\u00edcil del levantamiento.<\/p>\n\n\n\n<p>Dado que la parte m\u00e1s importante es la parte baja, debemos hacer el peso muerto tan profundo como podamos, obteniendo un buen estiramiento en los isquiosurales. Sin embargo, as\u00ed como la profundidad en la sentadilla, empezar un peso muerto desde el piso es completamente arbitrario. Empezar en una posici\u00f3n profunda es excelente, pero empezar <em>muy<\/em> profundo puede afectar a nuestra cadera y causar que nuestra espalda se doble. Como cada persona tiene una estructura y anatom\u00eda diferente, la profundidad ideal de cada uno ser\u00e1 un poco diferente.<\/p>\n\n\n\n<p>Para aquellos con una estructura \u00f3sea promedio y una postura decente, empezar el peso muerto desde el piso es la opci\u00f3n predeterminada. Casi todos nosotros podemos ubicarnos en una posici\u00f3n como el hombre de la izquierda:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"713\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2020\/04\/ilustracion-rayos-x-profundidad-peso-muerto.jpg\" alt=\"Ilustraci\u00f3n de dos personas; una con una estructura que le permite hacer un peso muerto convencional y otra que no.\" class=\"wp-image-1925\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2020\/04\/ilustracion-rayos-x-profundidad-peso-muerto.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2020\/04\/ilustracion-rayos-x-profundidad-peso-muerto-300x170.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2020\/04\/ilustracion-rayos-x-profundidad-peso-muerto-1024x579.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2020\/04\/ilustracion-rayos-x-profundidad-peso-muerto-768x435.jpg 768w, https:\/\/outlift.com\/wp-content\/uploads\/2020\/04\/ilustracion-rayos-x-profundidad-peso-muerto-320x180.jpg 320w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><figcaption>Algunas personas no tienen suficiente movilidad para el peso muerto convencional.<\/figcaption><\/figure>\n\n\n\n<p>Pero hablemos del hombre de la derecha. La mayor\u00eda de personas puede estar en una posici\u00f3n con las caderas dobladas a 110-130\u00ba (<a aria-label=\"source (opens in a new tab)\" href=\"http:\/\/web.mit.edu\/tkd\/stretch\/stretching_8.html#SEC90\" target=\"_blank\" rel=\"noreferrer noopener\">fuente<\/a>). El peso muerto t\u00edpicamente requiere alrededor de 115\u00b0 (<a href=\"https:\/\/www.strongerbyscience.com\/how-to-deadlift\/#How_to_correct_mobility_issues_or_spinal_flexion_issues\">fuente<\/a>). As\u00ed que, cuando algunas personas se preparan para el peso muerto, sus f\u00e9mures se chocan contra su pelvis, lo cual hace que la parte inferior de la espalda tenga que curvarse con el fin de llegar hasta la barra. Esto hace que la espalda pierda el alineamiento adecuado, haciendo que el levantamiento sea m\u00e1s peligroso.<\/p>\n\n\n\n<p>Si no tienes la movilidad para agarrar la barra sin que se doble la espalda, esto no quiere decir que no puedas hacer el peso muerto. Intenta los pasos de la siguiente lista, empezando desde el primer punto y siguiendo con los dem\u00e1s:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Peso muerto con barra hexagonal. <\/strong>La mayor\u00eda de barras hexagonales reducen el rango de movimiento por un par de pulgadas, y tambi\u00e9n reducen el grado de doblamiento en la cadera, aumentando el de las rodillas, lo cual permite que cualquier persona pueda ubicarse en la posici\u00f3n inicial adecuada. Pero, no todo el mundo tiene acceso a una de estas barra.<\/li><li><strong>Apunta tus rodillas hacia afuera. <\/strong>Para hacer esto, gira tus pies a alrededor de 30\u00b0, f\u00edjalos firmemente al piso, y luego \u00abatorn\u00edllalos\u00bb hacia adentro para que tus rodillas queden apuntando hacia afuera. Como siempre, alinea tus rodillas con el segundo dedo de los pies.<\/li><li><strong>Utiliza una posici\u00f3n convencional con los pies m\u00e1s separados<\/strong>, incluso si esto implica separar m\u00e1s a los brazos.<\/li><li><strong>Utiliza una posici\u00f3n sumo angosta<\/strong>, en la cual tus rodillas quedan justo afuera de tu agarre. Esta posici\u00f3n tiene mucho de los beneficios de un peso muerto convencional y libera un poco m\u00e1s de espacio en las caderas.<\/li><li><strong>Posici\u00f3n sumo<\/strong>, la cual requiere una movilidad mucho menor en las caderas.<\/li><li><strong>Peso muerto rumano. <\/strong>Esta variaci\u00f3n te permitir\u00e1 utilizar el rango de movimiento que sea c\u00f3modo para ti. La desventaja es que no es tan buena para fortalecer a la espalda como el peso muerto convencional.<\/li><\/ul>\n\n\n\n<p><strong>Por otro lado, si tienes una excelente movilidad, podr\u00edas hacer el peso muerto con una profundidad incluso mayor<\/strong><b>. <\/b>Para esto, podr\u00edas intentar el peso muerto con d\u00e9ficit, el peso muerto con agarre ancho o el peso muerto con agarre de <em>snatch<\/em> (arranque). Dado que requieren un mayor  \u00e1ngulo de inclinaci\u00f3n de la espalda, estas variaciones son a\u00fan mejores para construir una espalda superior m\u00e1s grande y fuerte.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1400\" height=\"742\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/snatch-grip-deadlift.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un peso muerto con agarre de snatch.\" class=\"wp-image-2211\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/snatch-grip-deadlift.jpg 1400w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/snatch-grip-deadlift-300x159.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/snatch-grip-deadlift-1024x543.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/snatch-grip-deadlift-768x407.jpg 768w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/><figcaption>El peso muerto con agarre ancho.<\/figcaption><\/figure>\n\n\n\n<p>Sin embargo, dado que con estas variaciones m\u00e1s profundas se debe utilizar menos peso, y debido a que el peso muerto es la mejor oportunidad que tenemos para cargar a nuestro cuerpo considerablemente, tal vez sea mejor dejar estas variaciones m\u00e1s profundas como levantamientos de asistencia.<\/p>\n\n\n\n<p><strong>Finalmente, una mezcla de diferentes rangos de movimiento probablemente es ideal.<\/strong> <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/24662234\">Un estudio de noviembre de 2014<\/a> encontr\u00f3 que incluir algunos levantamientos accesorios con un rango de movimiento parcial (como los <em>rack pulls<\/em>) junto con los levantamientos con un rango de movimiento completo (como el peso muerto), fue m\u00e1s efectivo para la ganancia de fuerza en comparaci\u00f3n con simplemente hacer un mayor volumen de los levantamientos con un rango de movimiento completo.<\/p>\n\n\n\n<p>As\u00ed que, si un peso muerto convencional es profundo para ti, incluye algunos levantamientos de asistencia con un rango de movimiento m\u00e1s corto. El peso muerto rumano es una excelente opci\u00f3n debido a que sigue trabajando a las caderas y a los isquiosurales en una posici\u00f3n estirada. Si el peso muerto convencional no es suficientemente profundo para ti, incluye algunos levantamientos de asistencia m\u00e1s profundos. El peso muerto con agarre ancho es una buena opci\u00f3n.<\/p>\n\n\n\n<p><strong>Para resumir, escoge como tu levantamiento principal al peso muerto m\u00e1s profundo que puedas hacer c\u00f3modamente. Para la mayor\u00eda de nosotros, un peso muerto convencional es la mejor opci\u00f3n. Junto a tu variaci\u00f3n principal, a\u00f1ade algunas variaciones con un rango de movimiento m\u00e1s profundo (agarre ancho) y menos profundo (rumano).<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"11-diagnosticando-eslabones-d%C3%A9biles\">Diagnosticando Eslabones D\u00e9biles<\/h3>\n\n\n\n<p>Hay algunos factores limitantes diferentes que son comunes en el peso muerto:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>No puedes levantar la barra del piso.<\/li><li>Fallas el levantamiento con la barra elevada unos pocos cent\u00edmetros.<\/li><li>La barra se resbala fuera de tus manos.<\/li><li>Fallas con la barra por encima de las rodillas.<\/li><li>Tu espalda se curva.<\/li><\/ul>\n\n\n\n<p>Ve\u00e1moslos uno por uno.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"12-la-barra-no-se-mueve\">La Barra no se Mueve<\/h4>\n\n\n\n<p><strong>Si la barra no se mueve, es posible que est\u00e9s utilizando mucho peso. <\/strong>En ese caso, utiliza menos peso. Simple.<\/p>\n\n\n\n<p><strong>Otra posibilidad es que la barra no se levanta debido a que los cu\u00e1driceps son desproporcionadamente d\u00e9biles. <\/strong>El peso muerto convencional principalmente entrena a las caderas y a la espalda, por lo cual no es com\u00fan que los cu\u00e1driceps sean un factor limitante, pero s\u00ed puede ocurrir Con la variaci\u00f3n sumo y con la barra hexagonal, los cu\u00e1driceps tienen un rol m\u00e1s importante, por lo cual es com\u00fan que la barra no se mueva del suelo por causa de cu\u00e1driceps d\u00e9biles.<\/p>\n\n\n\n<p>La soluci\u00f3n en este caso es hacer m\u00e1s sentadillas. Las sentadillas frontales y las sentadillas Zercher son buenas opciones debido a que con estas vamos a obtener un poco de crecimiento adicional de la espalda superior.<\/p>\n\n\n\n<p><strong>Tus caderas son muy d\u00e9biles.<\/strong> Si estas utilizando la posici\u00f3n convencional, tu espalda se mantienen en la posici\u00f3n adecuada, pero la barra simplemente no se levanta, probablemente tus caderas son muy d\u00e9biles. El peso muerto rumano, los buenos d\u00edas con barra baja y los empujes de cadera van a ayudar a resolver este problema.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"13-fallando-con-la-barra-levantada-unos-pocos-cent%C3%ADmetros\">Fallando con la Barra Levantada unos Pocos Cent\u00edmetros<\/h4>\n\n\n\n<p>Este es el escenario ideal. Esto significa que tus m\u00fasculos est\u00e1n desarrollados de forma proporcional y simplemente no son los suficientemente fuertes todav\u00eda.<\/p>\n\n\n\n<p>En este caso, no hay necesidad de hacer nada especial. Simplemente sigue volvi\u00e9ndote m\u00e1s fuerte en el patr\u00f3n de movimiento. El peso muerto convencional, el peso muerto rumano, los remos con barra y <u><font color=\"#000121\"><a aria-label=\"front-loaded squats (opens in a new tab)\" href=\"https:\/\/bonytobeastly.com\/front-squats-are-best-for-bulking\/\" target=\"_blank\" rel=\"noreferrer noopener\">flas sentadillas cargadas frontalmente<\/a><\/font><\/u>, van a ser \u00fatiles.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"14-problemas-de-agarre-en-el-peso-muerto\">Problemas de Agarre en el Peso Muerto<\/h4>\n\n\n\n<p><strong>Utiliza una t\u00e9cnica de agarre fuerte. <\/strong>Lo primero es asegurar que est\u00e9s utilizando un agarre mixto o un agarre de gancho, los cuales evitar\u00e1n que la barra ruede por fuera de tus manos.<\/p>\n\n\n\n<p>El agarre mixto es la forma en la que los levantadores de potencia agarran la barra. Este va a aumentar la activaci\u00f3n del b\u00edceps en el lado con la mano \u00abpor debajo\u00bb de la barra, as\u00ed que si cambias la posici\u00f3n de las manos entre series, este agarre puede a\u00f1adir un poco de trabajo de b\u00edceps adicional. Este agarre tambi\u00e9n aumenta el riesgo de desgarrar tus b\u00edceps, pero esto no es com\u00fan, y le ocurre principalmente a los levantadores de potencia que est\u00e1n intentando una repetici\u00f3n m\u00e1xima para una competencia. Tambi\u00e9n puedes reducir dr\u00e1sticamente el riesgo de desgarrar tus b\u00edceps manteniendo la parte superior de los brazos m\u00e1s relajada al hacer el peso muerto (lo cual deber\u00edas hacer en cualquier caso).<\/p>\n\n\n\n<p>El agarre de gancho es la forma en la que los levantadores de pesas ol\u00edmpicos agarran la barra. Este agarre te permitir\u00e1 hacer el peso muerto de forma m\u00e1s sim\u00e9trica, lo cual hace que sea m\u00e1s f\u00e1cil ejecutar el peso muerto con buena t\u00e9cnica, y tambi\u00e9n evita que tu columna gire o se tuerza.  Sin embargo, este agarre es doloroso. Cuando estaba aprendi\u00e9ndolo, mis pulgares estuvieron desgarrados y morados durante varios meses. Pero es la forma m\u00e1s vers\u00e1til y fuerte de agarrar una barra, y me gusta.<\/p>\n\n\n\n<p><strong>A\u00f1ade fricci\u00f3n a tus manos. <\/strong>Una vez que est\u00e9s utilizando un agarre fuerte, lo siguiente que debemos abordar es el sudor y lo resbaladizo de las manos. Intenta utilizar tiza (para cualquier agarre) o poniendo un poco de cinta para levantamiento alrededor de tu pulgar (para el agarre de gancho). Combinado con una buena t\u00e9cnica de agarre, esto usualmente ser\u00e1 suficiente.<\/p>\n\n\n\n<p>Si entrenas en un gimnasio comercial, es posible que la tiza no est\u00e9 permitida. No hay problema. Simplemente vas a tener que agarra la barra m\u00e1s fuerte (o empezar a utilizar un agarre de gancho con cinta en el pulgar).<\/p>\n\n\n\n<p><strong>Fortalece tu agarre.<\/strong> Si est\u00e1s utilizando una buena t\u00e9cnica de agarre y tiza\/cinta, y a\u00fan sigues teniendo problemas para sostener la barra, lo siguiente que puedes hacer es fortalecer tu agarre.<\/p>\n\n\n\n<p>Si la barra se resbala por fuera de tus manos al hacer un peso muerto, esto significa que no tienes la fuerza necesaria para mantener tus manos cerradas. S\u00ed, lo s\u00e9, un poco obvio. Pero, este es un tipo espec\u00edfico de fuerza de agarre denominado <em>fuerza de soporte<\/em>, que es diferente al tipo de fuerza que se utiliza al apretar cosas en las manos (fuerza de aplastamiento). Como resultado, requiere un tipo de entrenamiento espec\u00edfico.<\/p>\n\n\n\n<p>Hay algunas formas de fortalecer tu agarre, empezando con la m\u00e1s simple:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><b>Sigue un programa que utilice una variedad de levantamientos con barra. <\/b>Remos con barra, peso muerto rumano, chin-ups, caminatas con carga, y curls, todos van a ayudar a fortalecer tu agarre. Si tienes suficientes de estos ejercicios en tu programa, probablemente no vas a necesitar entrenamiento dedicado para el agarre. Pero, si tu agarre se est\u00e1 quedando atr\u00e1s, puede ser \u00fatil darle un mayor \u00e9nfasis.<\/li><li><strong>Agarre est\u00e1tico. <\/strong>Una vez que hayas terminado tus levantamientos pesados en la sesi\u00f3n, carga la barra y sostenla por 15-30 segundos. Haz 2-4 series. Cuando puedas sostener la barra por 30 segundos en la \u00faltima serie, a\u00f1ade un poco de peso en la siguiente sesi\u00f3n. Utiliza el mismo agarre que utilizas para el peso muerto (mixto o de gancho).<\/li><li><strong>Agarre est\u00e1tico con una mano.<\/strong> Si quieres mezclar un poco de entrenamiento para el abdomen con el entrenamiento para el agarre, puedes entrenar una mano a la vez. Esto es excelente para los oblicuos. (Esto funciona  mejor si est\u00e1s utilizando una barra que tenga moleteado central.)<\/li><li><strong>Colgadas con peso. <\/strong>Si tu espalda est\u00e1 fatigada del levantamiento pesado, es posible que prefieras colgarte de una barra en vez de los agarre est\u00e1ticos. No va a ser tan espec\u00edfico, y vas a tener que utilizar un agarre en supinaci\u00f3n con las dos manos, pero te permitir\u00e1 entrenar tu agarre sin estresar m\u00e1s a tu espalda. Nuevamente, haz estos al final de tus sesiones; cu\u00e9lgate de la barra por 15-30 segundos y a\u00f1ade peso cuando puedas colgarte por 30 segundos.<\/li><\/ul>\n\n\n\n<p>El truco es agarrar una barra  que tenga un di\u00e1metro similar a la barra con la que haces el peso muerto. S\u00ed puedes poner un mayor \u00e9nfasis en el agarre utilizando manijas m\u00e1s gruesas, pero la fuerza que ganes no se va a transferir tan bien al peso muerto.<\/p>\n\n\n\n<p><strong>Correas de levantamiento. <\/strong>Por supuesto, siempre est\u00e1 la opci\u00f3n de evitar los inconvenientes utilizando correas de levantamiento, las cuales son utilizadas por los <em>strongmen<\/em>. Perder\u00edas la oportunidad de fortalecer los m\u00fasculos de agarre con el peso muerto, pero es una opci\u00f3n. Si te ahorran tiempo y trabajo, tal vez valgan la pena para ti.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"15-fallando-con-la-barra-por-encima-de-las-rodillas\">Fallando con la Barra por Encima de las Rodillas<\/h4>\n\n\n\n<p>Fallar por encima de las rodillas usualmente est\u00e1 relacionado a la espalda curv\u00e1ndose. Graba un video de tu peso muerto y observa si tu espalda est\u00e1 saliendo del rango neutral. Si identificas que tu espalda se est\u00e1 curvando, mira la siguiente secci\u00f3n.<\/p>\n\n\n\n<p>Si tu espalda se mantiene en una buena posici\u00f3n, pero sigues teniendo problemas para finalizar el peso muerto, tenemos que fortalecer a tus caderas en esa parte superior del levantamiento. Los puentes de gl\u00fateos y los empujes de cadera son buenos para entrenar la fuerza de finalizaci\u00f3n de la cadera.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"16-la-espalda-se-curva\">La Espalda se Curva<\/h4>\n\n\n\n<p>Hay tres razones por las cuales tu espalda podr\u00eda estar curv\u00e1ndose durante el peso muerto.<\/p>\n\n\n\n<p><strong>Primero, no tienes la movilidad para ubicarte en la posici\u00f3n inicial.<\/strong> Esto podr\u00eda ser algo en lo que puedes trabajar, o simplemente son las caderas con las que naciste, como vimos previamente. En cualquier caso, no hay problema, simplemente puedes elevar la barra hasta el punto en el que puedas hacer el peso muerto sin que se curve tu espalda. Empezar a utilizar una barra hexagonal tambi\u00e9n puede ser una buena soluci\u00f3n a este problema.<\/p>\n\n\n\n<p><strong>Segundo, tus caderas no son suficientemente fuertes. <\/strong>Como vimos antes, curvar tu espalda durante el peso muerto abre el \u00e1ngulo de las caderas y las lleva m\u00e1s cerca a la barra, con lo cual obtienen un mejor apalancamiento.<\/p>\n\n\n\n<p>La primera desventaja es que esto hace que el peso muerto sea m\u00e1s peligroso y las segunda es que vas a tener mayor dificultad para completar la finalizaci\u00f3n. (Cuando las personas fallan con la barra por encima de las rodillas, una espalda curvando suele ser la ra\u00edz del problema.)<\/p>\n\n\n\n<p>Si esto es lo que est\u00e1 pasando, debes fortalecer tus caderas con el peso muerto rumano, puentes de gl\u00fateos, los empujes de caderas y los <i>glute-ham raises<\/i>.<\/p>\n\n\n\n<p><strong>Tercero, tus erectores de la columna no son suficientemente fuertes. <\/strong>El peso muerto convencional es un ejercicio para la espalda, as\u00ed que es completamente normal que tu espalda sea lo primero que se canse. Cuando sientas que tu espalda comienza a flexionarse (o sientas que est\u00e1 apunto de empezar a flexionarse) m\u00e1s de unos pocos grados, esta es una buena se\u00f1al para terminar tu serie. Tu espalda ya obtuvo lo que necesitaba del levantamiento.<\/p>\n\n\n\n<p>Para fortalecer a tu espalda, simplemente podr\u00edas hacer m\u00e1s de el peso muerto convencional. Despu\u00e9s de todo, si est\u00e1s fallando por causa de la fuerza de tu espalda, entonces tu espalda est\u00e1 obteniendo el mayor est\u00edmulo de crecimiento en el peso muerto. Pero, si est\u00e1s fallando por debido a tu espalda, lo m\u00e1s probable es que tu espalda ya est\u00e9 demasiado fatigada para soportar m\u00e1s volumen del peso muerto.<\/p>\n\n\n\n<p>Una mejor forma de fortalecerla ser\u00eda por medio de ejercicios m\u00e1s ligeros y f\u00e1ciles que estimulen el crecimiento de los m\u00fasculos de tu espalda sin generar tanta fatiga. Los buenos d\u00edas con barra alta, los remos con barra, las sentadillas cargadas frontalmente, y las hiper-extensiones pueden ser \u00fatiles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"17-alternativas-al-peso-muerto-convencional\">Alternativas al Peso Muerto Convencional<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"18-el-peso-muerto-sumo\">El Peso Muerto Sumo<\/h3>\n\n\n\n<p><strong>El peso muerto te permite levantar utilizando m\u00e1s de las piernas y menos de la espalda.<\/strong> Es m\u00e1s f\u00e1cil para los erectores de la columna, m\u00e1s f\u00e1cil para los trapecios medios y bajos, y es m\u00e1s f\u00e1cil para los dorsales. Sin embargo, sigue siendo igual de dif\u00edcil para las caderas y los isquiosurales, y es un ejercicio sorprendentemente bueno para los cu\u00e1driceps.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"691\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/sumo-deadlift-illustration-on-white.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un peso muerto sumo.\" class=\"wp-image-1388\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/sumo-deadlift-illustration-on-white.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/sumo-deadlift-illustration-on-white-300x165.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/sumo-deadlift-illustration-on-white-1024x562.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/sumo-deadlift-illustration-on-white-768x421.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<p><strong>La mayor\u00eda de personas decide hacer el peso muerto sumo en vez del convencional por las razones equivocadas. <\/strong>Cambian de variaci\u00f3n debido a que, cuando hacen el peso muerto convencional, es dif\u00edcil mantener una espalda recta, sienten una molestia en la espalda, o sienten que el levantamiento est\u00e1 involucrando mucho a los erectores de la columna. Estas son malas razones para cambiar a la variaci\u00f3n sumo.<\/p>\n\n\n\n<p>El peso muerto convencional es, en gran parte, un ejercicio para la espalda, por lo cual el hecho de que desaf\u00ede a la espalda no es ninguna indicaci\u00f3n de que deber\u00edas hacer una variaci\u00f3n diferente. Eso ser\u00eda como cambiar el press de banca por extensiones de tr\u00edceps, debido a que el press es dif\u00edcil para el pecho. As\u00ed como el press de banca deber\u00eda ser dif\u00edcil para el pecho, el peso muerto convencional deber\u00eda ser dif\u00edcil para la espalda.<\/p>\n\n\n\n<p>Algunas personas dicen que si tu espalda est\u00e1 teniendo problemas para soportar las demandas del peso muerto convencional, tu espalda se est\u00e1 identificando como un punto d\u00e9bil que requiere de atenci\u00f3n. As\u00ed que, deber\u00edas seguir haciendo el peso muerto convencional, a\u00f1adir algunos levantamientos de asistencia y accesorios para la espalda (como los buenos d\u00edas y los remos con barra), y dejar que tu espalda crezca.<\/p>\n\n\n\n<p>Pero, siendo honestos, el peso muerto sumo es suficientemente similar al peso muerto convencional que, si lo prefieres, no va a arruinar tus resultados. Aunque t\u00e9cnicamente no es ideal para ganar tama\u00f1o y fuerza en la espalda, ni para mejorar tu est\u00e9tica, el peso muerto sumo no es tan diferente al convencional como para arruinar completamente tu progreso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"19-el-peso-muerto-con-barra-hexagonal\">El Peso Muerto con Barra Hexagonal<\/h3>\n\n\n\n<p><strong>El peso muerto con barra hexagonal es, probablemente, el mejor levantamiento para ganar m\u00fasculo y mejorar la fuerza general\u2014con un detalle. <\/strong>Es una combinaci\u00f3n entre un peso muerto convencional, una caminata con carga, y una sentadilla:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>As\u00ed como en el peso muerto convencional, se utiliza una parada angosta. <\/strong>Tambi\u00e9n puedes sentarte \u00abhacia atr\u00e1s\u00bb para que sea un levantamiento con \u00e9nfasis en la cadera, como lo har\u00edas al hacer un peso muerto convencional.<\/li><li><strong>As\u00ed como en la caminata con carga, el peso se sostiene a los lados con un agarre neutral.<\/strong> M\u00e1s a\u00fan, la barra hexagonal est\u00e1 dise\u00f1ada de tal forma que las manijas no van a intentar girar a tus manos, lo cual hace que sea <em>mucho m\u00e1s f\u00e1cil<\/em> sostener la barra. Esto implica que no vas a tener que utilizar un agarre mixto, de gancho o tiza.<\/li><li><strong>As\u00ed como en la sentadilla, debido a que la barra no est\u00e1 en el camino, las rodillas pueden moverse hacia el frente con libertad, con lo cual puedes involucrar a los cu\u00e1driceps para levantar el peso. <\/strong>Tambi\u00e9n es menos demandante para la espalda inferior, debido a que puedes mantener una posici\u00f3n m\u00e1s vertical del torso.<\/li><\/ul>\n\n\n\n<p>Por esto, el peso muerto con barra hexagonal es un levantamiento <em>incre\u00edble<\/em> para el desarrollo de fuerza global. Es excelente para la cadena posterior <em>y<\/em> para los cu\u00e1driceps. Sin embargo, el peso muerto con barra hexagonal no es <em>tan <\/em>bueno para los isquiosurales, la espalda y los antebrazos, como la variaci\u00f3n convencional, y al fin y al cabo, ya tenemos a <a href=\"https:\/\/outlift.com\/es\/sentadilla-guia-para-ganar-musculo\/\">la sentadilla<\/a> para nuestros cu\u00e1driceps.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"799\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/diferencia-brazo-momento-convencional-vs-sumo-vs-hexagonal.jpg\" alt=\"Ilustraci\u00f3n de la diferencia entre el peso muerto convencional, el peso muerto sumo, y el peso muerto con barra hexagonal.\" class=\"wp-image-6383\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/diferencia-brazo-momento-convencional-vs-sumo-vs-hexagonal.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/diferencia-brazo-momento-convencional-vs-sumo-vs-hexagonal-300x190.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/diferencia-brazo-momento-convencional-vs-sumo-vs-hexagonal-1024x649.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/diferencia-brazo-momento-convencional-vs-sumo-vs-hexagonal-768x487.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<p>M\u00e1s a\u00fan, dado que las manijas est\u00e1n m\u00e1s arriba, el peso muerto con barra hexagonal utilizar un menor rango de movimiento que todas las otras variaciones. Un rango de movimiento menor no <em>siempre<\/em> es algo malo, simplemente depende de lo que queramos lograr. Pero, en este caso, el menor rango de movimiento probablemente reduce el crecimiento muscular que vamos a estimular. El menor rango de movimiento tambi\u00e9n har\u00e1 que esta variaci\u00f3n sea peor para mejorar nuestra capacidad de trabajo, la cual es una gran ventaja del peso muerto convencional.<\/p>\n\n\n\n<p>As\u00ed que, aunque el peso muerto con barra hexagonal posiblemente es el mejor levantamiento a nivel global para el tren inferior, probablemente vas a obtener un mejor retorno a la inversi\u00f3n haciendo el peso muerto convencional y sentadillas frontales.<\/p>\n\n\n\n<p>A menos de que hagas el peso muerto con barra hexagonal como si fuera un peso muerto convencional. Despu\u00e9s de todo, puedes conseguir una barra con manijas m\u00e1s cortas, sentarte m\u00e1s hacia atr\u00e1s en la posici\u00f3n inicial y luego levantar el peso con la cadena posterior. En este caso, b\u00e1sicamente estar\u00edas haciendo un peso muerto convencional pero con una barra hexagonal.<\/p>\n\n\n\n<p>Utilizar una t\u00e9cnica de peso muerto convencional con una barra hexagonal tambi\u00e9n tiene otras ventajas interesantes:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Vas a tener los brazos en una posici\u00f3n m\u00e1s neutral, lo cual puede ser bueno para los hombros.<\/li><li>Tu agarre ser\u00e1 m\u00e1s ancho, lo cual es excelente para los trapecios.<\/li><li>No tienes que preocuparte por que la barra vaya a rodar por fuera de tus manos.<\/li><\/ul>\n\n\n\n<p>Si haces un peso muerto con un estilo convencional pero con una barra hexagonal, yo lo contar\u00eda como un peso muerto convencional. Seguir\u00edas obteniendo todos los beneficios.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"20-el-peso-muerto-rumano\">El Peso Muerto Rumano<\/h3>\n\n\n\n<p>El peso muerto rumano consiste en la mitad superior de un peso muerto convencional, y se inicia de pie. Se hace bajando la barra hasta las rodillas, y luego levant\u00e1ndola con las caderas, as\u00ed:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"1278\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-peso-muerto-rumano.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un peso muerto rumano.\" class=\"wp-image-6385\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-peso-muerto-rumano.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-peso-muerto-rumano-296x300.jpg 296w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-peso-muerto-rumano-1010x1024.jpg 1010w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-peso-muerto-rumano-768x779.jpg 768w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-peso-muerto-rumano-70x70.jpg 70w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<p>Dado que la barra no se baja hasta el piso, esta variaci\u00f3n mantiene al torso en una posici\u00f3n m\u00e1s recta, reduciendo la demanda sobre la espalda inferior, tanto en t\u00e9rminos de pico de carga (parte baja del levantamiento) como carga promedio (a lo largo de todo el rango de movimiento):<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"916\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazo-de-momento-peso-muerto-convencional-vs-rumano.jpg\" alt=\"Ilustraci\u00f3n de la diferencia en el brazo de momento del peso muerto convencional y del peso muerto rumano.\" class=\"wp-image-6387\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazo-de-momento-peso-muerto-convencional-vs-rumano.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazo-de-momento-peso-muerto-convencional-vs-rumano-300x218.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazo-de-momento-peso-muerto-convencional-vs-rumano-1024x744.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazo-de-momento-peso-muerto-convencional-vs-rumano-768x558.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<p>Esto, combinado con el hecho de que el peso muerto rumano es sustancialmente m\u00e1s ligero que un peso muerto completo, hace que esta variaci\u00f3n genere una cantidad de fatiga <em>mucho<\/em> menor, pero sigue siendo similarmente buena para estimular el crecimiento de las caderas y los isquiosurales.<\/p>\n\n\n\n<p>Sin embargo, la mayor\u00eda de personas quiere utilizar el peso muerto para estimular el crecimiento del tren superior y para fortalecer a los huesos. El peso muerto rumano no es muy bueno para esto. Como resultado, generalmente lo utilizamos como un levantamiento de asistencia y no como nuestros levantamiento principal. Pero, si por alguna raz\u00f3n ninguna de las variaciones de peso muerto pesadas te funcionan, el peso muerto rumano es una buena opci\u00f3n secundaria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"21-alternativas-con-el-peso-corporal\">Alternativas con el Peso Corporal<\/h2>\n\n\n\n<p>Encontrar buenas alternativas al peso muerto utilizando s\u00f3lo el peso corporal es un poco complicado, debido a que algunos de los principales beneficios del peso muerto provienen de la carga pesada sobre nuestra columna, trapecios y erectores de la columna. Por esto, sin la carga pesada, no vamos a poder imponer tanto estr\u00e9s sobre nuestra columna ni estimular tanto crecimiento muscular en nuestros trapecios y erectores de la columna. A\u00fan as\u00ed, hay algunas variaciones de peso muerto con el peso corporal que son excelentes para ganar m\u00fasculo en los isquiosurales y los gl\u00fateos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Peso muerto con peso corporal con toalla <\/li><li>Peso muerto rumano a una pierna<\/li><li>Empuje de cadera a una pierna<\/li><li>Puentes con piernas extendidas<\/li><\/ul>\n\n\n\n<p>Cualquier cosa que desaf\u00ede la fuerza o capacidad de trabajo de nuestros m\u00fasculos puede provocar crecimiento muscular. Sin embargo, debemos tener los principios de hipertrofia en mente al intentar ganar m\u00fasculo con el entrenamiento con peso corporal:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Deber\u00edamos seguir utilizando rangos de repeticiones moderados (5-40 repeticiones por serie): <\/strong>si hacemos m\u00e1s de veinte repeticiones por serie, nuestra tolerancia al dolor puede volverse un factor limitante en vez de nuestra fuerza muscular. Si hacemos m\u00e1s de <em>cuarenta<\/em> repeticiones por serie, vamos a estimular adaptaciones en nuestra condici\u00f3n f\u00edsica en vez de nuestro tama\u00f1o y fuerza muscular.<\/li><li><strong>Debemos asegurarnos de que el equilibrio no sea el factor limitante: <\/strong>si estamos m\u00e1s concentrado en mantener el equilibrio que en trabajar a los m\u00fasculos, no vamos a estar limitados por nuestra fuerza, por lo cual no vamos a provocar crecimiento muscular.<\/li><li><strong>Debemos entrenar cerca al fallo <em>muscular<\/em>: <\/strong>al hacer el peso muerto con peso en rangos de repeticiones moderados de 4-10, nuestros m\u00fasculos usualmente van a tirar la toalla antes de que la serie se vuelva extremadamente dif\u00edcil a nivel cardiovascular o dolorosa. Sin embargo, con el entrenamiento con peso corporal, debido a que los rangos de repeticiones pueden ser tan altos, es m\u00e1s probable que acabemos nuestras series por causa de la fatiga o el dolor. Para asegurar que estamos estimulando el crecimiento muscular, debemos perseverar hasta que m\u00fasculos comiencen a agotarse.<\/li><li><strong>Deber\u00edamos intentar desafiar a nuestros m\u00fasculos en una posici\u00f3n estirada: <\/strong>una de las razones por las cuales el peso muerto es tan bueno para estimular la hipertrofia muscular es que desaf\u00eda a nuestros gl\u00fateos e isquiosurales en una posici\u00f3n estirada en la parte baja del levantamiento.<\/li><\/ul>\n\n\n\n<p>As\u00ed que, cuando se trata de escoger variaciones del peso muerto con peso corporal, tenemos que escoger variaciones que sean suficientemente pesadas para causar el fallo muscular antes de cuarenta repeticiones, e idealmente antes de veinte repeticiones. Tambi\u00e9n tenemos que asegurarnos de que el ejercicio no implica una demanda de equilibrio muy grande, de tal forma que este no sea lo que nos limite (lo cual puede ser un problema con las variaciones a una pierna). Y adem\u00e1s, idealmente queremos desafiar a nuestros m\u00fasculos en la parte profunda del rango de movimiento. Pero, si podemos hacer esto, vamos a poder estimular el crecimiento de los isquiosurales y los gl\u00fateos en buena medida.<\/p>\n\n\n\n<p>La forma m\u00e1s f\u00e1cil de hacer que el peso muerto con peso corporal sea m\u00e1s dif\u00edcil, es entrenando una pierna a la vez (unilateralmente). Si podemos hacer cuarenta puentes de gl\u00fateos seguidos, es posible que s\u00f3lo podamos hacer veinte a una pierna (por cada lado). Por esto, las mejores variaciones con peso corporal tienden a ser ejercicios unilaterales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"22-el-peso-muerto-con-peso-corporal-con-toalla\">El Peso Muerto con Peso Corporal con Toalla<\/h3>\n\n\n\n<p>La mayor\u00eda de alternativas al peso muerto con peso corporal no nos permiten cargar al cuerpo como con las series pesadas de pocas repeticiones, no desaf\u00edan a nuestros gl\u00fateos ni isquiosurales en una posici\u00f3n estirada, <em>y no trabajan a los erectores de la columna ni a los trapecios.<\/em> El peso muerto con toalla resuelve todos estos problemas, permiti\u00e9ndonos estimular a nuestra cadena posterior con tan s\u00f3lo una toalla.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"858\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/bodyweight-towel-deadlift-alternative.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un peso muerto con toalla.\" class=\"wp-image-2431\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/bodyweight-towel-deadlift-alternative.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/bodyweight-towel-deadlift-alternative-300x204.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/bodyweight-towel-deadlift-alternative-1024x697.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/bodyweight-towel-deadlift-alternative-768x523.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<p>El peso muerto con toalla se realiza poniendo una toalla debajo de los pies y jal\u00e1ndola, as\u00ed como jalar\u00edamos una barra. La diferencia es que este es un ejercicio isom\u00e9trico\u2014no hay rango de movimiento. No importa qu\u00e9 tan fuertemente jales la toalla, no se va a mover. Estamos fijos en esa posici\u00f3n baja. Y eso est\u00e1 bien.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"680\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/grafico-diferencia-crecimiento-carga-estiramiento-contraccion.jpg\" alt=\"Gr\u00e1fico mostrando la diferencia en crecimiento muscular al entrenar a los m\u00fasculos en una posici\u00f3n contra\u00edda y estirada.\" class=\"wp-image-6181\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/grafico-diferencia-crecimiento-carga-estiramiento-contraccion.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/grafico-diferencia-crecimiento-carga-estiramiento-contraccion-300x162.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/grafico-diferencia-crecimiento-carga-estiramiento-contraccion-1024x553.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/grafico-diferencia-crecimiento-carga-estiramiento-contraccion-768x414.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<p>De hecho, si miramos los resultados de un <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/30580468\" target=\"_blank\" rel=\"noreferrer noopener\">meta-an\u00e1lisis<\/a> que eval\u00fao la efectividad de los isom\u00e9tricos para la hipertrofia muscular, podemos ver que los isom\u00e9tricos que desaf\u00edan a los m\u00fasculos en una posici\u00f3n estirada son bastante buenos para estimular el crecimiento muscular. Esta variaci\u00f3n del peso muerto desaf\u00eda m\u00e1ximamente a las caderas y a los isquiosurales en una posici\u00f3n estirada, por lo cual podemos esperar  que sean buena para el crecimiento muscular. Dado que podemos agarrar la toalla a cualquier altura, podemos ubicarnos de forma intencional en una posici\u00f3n que estire al m\u00e1ximo a nuestros isquiosurales.<\/p>\n\n\n\n<p>El otro beneficio del peso muerto con toalla es que toda la cadena posterior est\u00e1 involucrada. A medida que jalamos la toalla, los erectores de la columna y los m\u00fasculos en la mitad de la espalda necesitan trabajar igual de fuerte a como lo har\u00edan si estuvi\u00e9ramos jalando una barra cargada con m\u00e1s peso del que podemos levantar. Es un ejercicio verdaderamente de cuerpo completo. <\/p>\n\n\n\n<p>Para hacer el peso muerto con toalla, recomendamos utilizar repeticiones cortas. Jala tan fuerte como puedas por algunos segundos y detente. Esa es la primera repetici\u00f3n. Luego vuelve a jalar tan fuerte como puedas por algunos segundos y detente. Esta es la segunda repetici\u00f3n. Puedes aumentar el n\u00famero de segundos durante los cuales jalas y puedes ajustar el n\u00famero de repeticiones que hacer por serie. Por ejemplo:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Semana Uno: <\/strong>3 series de 3 repeticiones (3\u00d73), y cada repetici\u00f3n dura cinco segundos.<\/li><li><strong>Semana Dos: <\/strong>4 series de 3 repeticiones (4\u00d73), y cada repetici\u00f3n dura seis segundos.<\/li><li><strong>Semana Tres: <\/strong>4 series de 4 repeticiones (4\u00d74), y cada repetici\u00f3n dura siete segundos.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"23-el-empuje-de-cadera\">El Empuje de Cadera<\/h3>\n\n\n\n<p>Los empujes de cadera son decentes para ganar tama\u00f1o y fuerza en los gl\u00fateos, y nuestros isquiosurales tambi\u00e9n van a obtener un poco de estimulaci\u00f3n. El problema es que el empuje de cadera es f\u00e1cil en la parte baja, cuando nuestro m\u00fasculos est\u00e1n estirados, y dif\u00edcil en la parte alta, en donde nuestros m\u00fasculos est\u00e1n contra\u00eddos. Esta es la peor curva de fuerza para ganar m\u00fasculo. Esto no implica que sea un ejercicio in\u00fatil, pero implica que es una mala opci\u00f3n para escogerlo como nuestro levantamiento principal. Es mejor utilizarlo como un levantamiento accesorio para los gl\u00fateos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1400\" height=\"797\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/one-legged-hip-thrust-illustration.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un empuje de cadera con peso corporal a una pierna\" class=\"wp-image-2445\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/one-legged-hip-thrust-illustration.jpg 1400w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/one-legged-hip-thrust-illustration-300x171.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/one-legged-hip-thrust-illustration-1024x583.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/one-legged-hip-thrust-illustration-768x437.jpg 768w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/><\/figure>\n\n\n\n<p>Hay diversas variaciones de empuje de cadera, con un grado de dificultad diferente:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li><strong>Puente de Gl\u00fateos: <\/strong>empieza con puentes de gl\u00fateos normales, hasta que puedas hacer al menos veinte repeticiones; si quieres, puedes seguir haci\u00e9ndolos hasta que puedas hacer cuarenta repeticiones.<\/li><li><strong>Puente de Gl\u00fateos a una pierna:<\/strong> una vez que puedas hacer 20-40 repeticiones con ambas piernas apoyadas en el piso, empieza a hacer la variaci\u00f3n a una pierna y progresa nuevamente hasta las 20-40 repeticiones.<\/li><li><strong>Empuje de Cadera:<\/strong> cuando puedas hacer 20-40 repeticiones de puentes de gl\u00fateos a una pierna, empieza a hacer empujes de cadera con la espalda sobre un banco. Puedes poner una maleta llena de libros sobre tu regazo para hacer que el ejercicio sea m\u00e1s dif\u00edcil.<\/li><li><strong>Empuje de Cadera a una pierna: <\/strong>cuando puedas hacer 20-40 repeticiones, empieza a hacer el ejercicio con una pierna a la vez, y vuelve a progresar hasta las cuarenta repeticiones.<\/li><\/ol>\n\n\n\n<p>As\u00ed que, si quieres aumentar el tama\u00f1o de tus caderas espec\u00edficamente, el empuje de cadera puede ser una alternativa de peso corporal razonable para el peso muerto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"24-levantamientos-de-asistencia\">Levantamientos de Asistencia<\/h2>\n\n\n\n<p>El peso muerto convencional pesado es incre\u00edblemente fatigante, especialmente una vez que eres considerablemente fuerte, y especialmente si est\u00e1s exigi\u00e9ndote en gran medida. De hecho, para la mayor\u00eda de personas, el peso muerto genera el <em>doble<\/em> de la fatiga que las sentadillas. Por esto, la mayor\u00eda s\u00f3lo puede hacer el peso muerto una vez por semana.<\/p>\n\n\n\n<p>Hacerlo m\u00e1s de una vez a la semana puede ser demasiado para los discos de la columna, muy estresante para los erectores de la columna, y desgasta a nuestra manos excesivamente. Y es agotante en general. Nadie quiere sentirse destrozado toda la semana.<\/p>\n\n\n\n<p>Sin embargo, entrenar un patr\u00f3n de movimiento s\u00f3lo una vez a la semana no es ideal para ganar m\u00fasculo o fuerza. Esto significa que si queremos tener una frecuencia dentro del rango \u00abideal\u00bb (2-3 veces por semana), deber\u00edamos hacer uso de levantamientos de asistencia y accesorios. Estos nos pueden ayudar a estimular a los m\u00fasculos relevantes sin acumular tanta fatiga general.<\/p>\n\n\n\n<p>Lo siguiente que debemos considerar es si los erectores de la columna necesitan m\u00e1s o menos trabajo.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>El argumento a favor de <em>m\u00e1s <\/em>trabajo para los erectores. <\/strong>Dedicar m\u00e1s tiempo a aumentar el tama\u00f1o de los erectores de la columna va a hacer que el peso muerto sea menos estresante para la espalda, con lo cual no vas a sentirte tan destruido o vas a poder tolerar un mayor volumen de peso muerto. En este caso, podr\u00edas beneficiarte de hacer remos con barra, buenos d\u00edas, e hiperextensiones.<\/li><li><strong>El argumento en contra de <em>menos<\/em> trabajo para los erectores. <\/strong>Por otra parte, si tus erectores de la columna ya est\u00e1n siendo llevados a sus l\u00edmites, podr\u00eda ser mejor darles un descanso durante el resto de la semana. En este caso, ser\u00edan mejor los levantamientos que minimizan el rol de los erectores de la columna, para darles m\u00e1s tiempo para recuperarse.<\/li><\/ul>\n\n\n\n<p>Lo mejor probablemente consiste en un poco de ambas opciones. Escoge un par de levantamientos que fortalezcan a los erectores, pero que no sean excesivamente exigentes. Y evita los levantamientos que causen mucha fatiga en la espalda inferior.<\/p>\n\n\n\n<p>Otra opci\u00f3n es tener un menor volumen del peso muerto y aumentar el volumen de los levantamientos de asistencia. Por ejemplo, tal vez hagas 4-5 series de sentadillas por sesi\u00f3n, pero s\u00f3lo haces tres series de peso muerto. Para abordar la disparidad, incluir\u00edas m\u00e1s remos y m\u00e1s series de peso muerto rumano, y menos accesorios para la sentadilla.<\/p>\n\n\n\n<p>Finalmente, si te est\u00e1s sintiendo destrozado antes de una sesi\u00f3n pesada de peso muerto, considera intercambiarlo por un levantamiento de asistencia. Por ejemplo, si tu espalda inferior se est\u00e1 sintiendo fatigada antes de empezar tus series de peso muerto convencional, considera cambiarlo por el peso muerto rumano en esa sesi\u00f3n. Este ser\u00e1 m\u00e1s f\u00e1cil para la espalda y va a permitir que, si todo sale bien, te sientas bien para la siguiente semana.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"25-el-peso-muerto-rumano-a-una-pierna\">El Peso Muerto Rumano a una Pierna<\/h3>\n\n\n\n<p>Lo importante al escoger los ejercicios de asistencia para el peso muerto es que queremos minimizar el estr\u00e9s sobre la espalda. Lo que queremos es estimular a los erectores de la columna tanto como sea posible sin acumular m\u00e1s estr\u00e9s del que sea puedan recuperar. Tambi\u00e9n queremos mantener el estr\u00e9s sobre los discos de la columna a un nivel manejable.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1400\" height=\"970\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/one-legged-romanian-deadlift.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un peso muerto rumano a una pierna.\" class=\"wp-image-2214\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/one-legged-romanian-deadlift.jpg 1400w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/one-legged-romanian-deadlift-300x208.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/one-legged-romanian-deadlift-1024x709.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/one-legged-romanian-deadlift-768x532.jpg 768w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/><\/figure>\n\n\n\n<p>Una opci\u00f3n que cumple con esos objetivos es el peso muerto rumano a una pierna. Al entrenar una pierna a la vez podemos obtener la misma estimulaci\u00f3n sobre las caderas y los isquiosurales pero utilizando un peso mucho menor. Los erectores de la columna siguen siendo trabajados, pero con un peso sustancialmente menor y con el doble de las series. Esto incluso puede ser una forma de recuperaci\u00f3n activa, permiti\u00e9ndoles sanar y adaptarse de forma m\u00e1s r\u00e1pida.<\/p>\n\n\n\n<p>Lo mismo es cierto para los antebrazos. Sostenemos mucho menos peso, pero con el doble de series, lo cual parece ser una gran forma de manejar la fatiga y la recuperaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"26-el-peso-muerto-con-agarre-ancho\">El Peso Muerto con Agarre Ancho<\/h3>\n\n\n\n<p>Utilizar un agarre m\u00e1s ancho en el peso muerto implica un par de cosas. Primero, nos obliga a inclinarnos m\u00e1s, extendiendo el rango de movimiento para las caderas. Segundo, hace que nuestra espalda quede en una posici\u00f3n m\u00e1s horizontal, haciendo que el levantamiento sea mejor para fortalecer a los erectores de la columna. Tercero, pone a casi todos los m\u00fasculos de la espalda superior en una posici\u00f3n dif\u00edcil, forz\u00e1ndolos a trabajar mucho m\u00e1s.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1400\" height=\"742\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/snatch-grip-deadlift.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un peso muerto con agarre de snatch.\" class=\"wp-image-2211\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/snatch-grip-deadlift.jpg 1400w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/snatch-grip-deadlift-300x159.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/snatch-grip-deadlift-1024x543.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/snatch-grip-deadlift-768x407.jpg 768w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/><\/figure>\n\n\n\n<p>Ahora bien, todo esto implica que se debe utilizar menos peso. Como resultado, utilizar un peso muerto con agarre ancho no necesariamente es mejor que el peso muerto convencional para estimular crecimiento muscular global. Sin embargo, es una excelente forma de obtener una gran cantidad de crecimiento muscular utilizando un peso menor, por lo cual es un excelente levantamiento de asistencia.<\/p>\n\n\n\n<p>Yo escoger\u00eda el peso muerto con agarre ancho si quieres acelerar el desarrollo de tu espalda superior. Si quisieras, por ejemplo, trapecios m\u00e1s grandes, este ser\u00eda un excelente levantamiento de asistencia.<\/p>\n\n\n\n<p>Ahora bien, hay un tipo de peso muerto con agarre ancho popular, llamado peso muerto con agarre de <em>snatch <\/em>(arrancada). Esta es una buena variaci\u00f3n que t\u00edpicamente se utiliza para mejorar el rendimiento en el levantamiento ol\u00edmpico. El detalle es que el peso muerto con agarre de <em>snatch<\/em> se realiza con un agarre <em>muy<\/em> ancho, lo cual podr\u00eda extender el rango de movimiento m\u00e1s de lo que puedes manejar. Puede ser que no. Puedes intentarlo para ver c\u00f3mo se siente, pero recuerda que puedes utilizar un agarre que sea menos ancho si se siente m\u00e1s c\u00f3modo. A m\u00ed me gusta poner mis me\u00f1iques sobre las marcas de moleteado para el press de banca.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"27-la-sentadilla-frontal-sentadilla-zercher-\">La Sentadilla Frontal \/ Sentadilla Zercher <\/h3>\n\n\n\n<p>Las sentadillas traseras trabajan a muchos de los mismos m\u00fasculos que se utilizan en el peso muerto, incluyendo a los cu\u00e1driceps gl\u00fateos, erectores de la columna y dorsales. Sin embargo, algunos expertos, como Greg Nuckols, MA, consideran que la fuerza que se gana al hacer sentadillas traseras, no se transfiere bien a la fuerza en el peso muerto. Su razonamiento es que los factores limitantes en la sentadilla trasera son muy diferentes a los del peso muerto.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"730\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/zercher-squat-illustration-outlift.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo una sentadilla Zercher.\" class=\"wp-image-1399\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/zercher-squat-illustration-outlift.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/zercher-squat-illustration-outlift-300x174.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/zercher-squat-illustration-outlift-1024x593.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2019\/12\/zercher-squat-illustration-outlift-768x445.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<p>Por ejemplo, digamos que tus cu\u00e1driceps son tu grupo muscular limitante en la sentadilla trasera, y los erectores de la columna son tu grupo muscular limitante en el peso muerto. Para hacer sentadillas, los erectores de la columna son suficientemente fuertes, por lo cual no van a crecer. Ser\u00e1n los cu\u00e1driceps los que crezcan.<\/p>\n\n\n\n<p>Al hacer el peso muerto, s\u00ed, vas a tener cu\u00e1driceps m\u00e1s fuertes debido a las sentadillas, pero estos no te estaban limitando en el peso muerto. Tu factor limitante en el peso muerto siguen siendo los erectores de la columna, y las sentadillas no han estimulado su crecimiento.<\/p>\n\n\n\n<p>Sin embargo, no todas las sentadillas son iguales. Algunas variaciones demandan mucho m\u00e1s de los erectores de la columna que otras. Aqu\u00ed es d\u00f3nde las sentadillas cargadas frontalmente tienen un rol. Como mencionamos en el <a href=\"https:\/\/outlift.com\/es\/sentadilla-guia-para-ganar-musculo\/\">art\u00edculo sobre la sentadilla<\/a>, las sentadillas frontales son tan buena para la espalda superior como lo son para los cu\u00e1driceps, lo cual las convierte en un levantamiento accesorio excelente para el peso muerto.<\/p>\n\n\n\n<p>Por supuesto, el beneficio adicional es que pasar\u00edamos m\u00e1s tiempo haciendo sentadillas, con lo cual tambi\u00e9n mejoraremos nuestro rendimiento en la sentadilla.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"28-levantamientos-accesorios\">Levantamientos Accesorios<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"29-remos-con-barra\">Remos con Barra<\/h3>\n\n\n\n<p>Los remos con barra son bastante similares al peso muerto. Ambos trabajan a los mismos m\u00fasculos: el agarre, los erectores de la columna, los gl\u00fateos y los isquiosurales La diferencia es que en el peso muerto el movimiento viene de las caderas y el soporte de la espalda, mientras que en el remo el movimiento viene de la espalda y el soporte de las caderas.<\/p>\n\n\n\n<p>Debido a que levantar un peso tiende a causar m\u00e1s crecimiento muscular que estabilizarlo, el remo con barra tiende a ser mejor para desarrollar a los dorsales, mientras que el peso muerto es mejor para desarrollar a las caderas. Sin embargo, para un crecimiento \u00f3ptimo, lo ideal es hacer ambos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"951\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/remo-con-barra-clasico.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un remo con barra cl\u00e1sico.\" class=\"wp-image-6217\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/remo-con-barra-clasico.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/remo-con-barra-clasico-300x226.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/remo-con-barra-clasico-1024x773.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/remo-con-barra-clasico-768x580.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<p>El remo con barra cl\u00e1sico, en el cual te ubicas en una posici\u00f3n similar a la del peso muerto rumano (con la barra a la altura de las rodillas) y llevas la barra hasta el est\u00f3mago o el estern\u00f3n, es una buena opci\u00f3n. Es un levantamiento relativamente f\u00e1cil, y es excelente para el crecimiento de los dorsales y los antebrazos.<\/p>\n\n\n\n<p>Ahora bien, vale la pena mencionar que, aunque los remos trabajan a los dorsales, esto no es lo que los hace compatibles con el peso muerto; los dorsales no est\u00e1n conectados a las v\u00e9rtebras de la columna, por lo cual no van a ayudarnos a mantener la posici\u00f3n de la columna al hacer un peso muerto. Lo que hace que los remos tengan tan buena transferencia al peso muerto, es que tambi\u00e9n van a estimular el crecimiento de los erectores de la columna y de las caderas. Esto significa que escoger variaciones como los remos con soporte del pecho o con un brazo apoyado no van a tener el mismo beneficio. Estas variaciones son accesorios para el <a href=\"https:\/\/outlift.com\/es\/chin-ups-guia-para-ganar-musculo\/\">chin-up<\/a>.<\/p>\n\n\n\n<p>Esto tambi\u00e9n implica que las variaciones de remo que ponen incluso m\u00e1s \u00e9nfasis sobre las caderas y los erectores de la columna pueden tener a\u00fan m\u00e1s transferencia al peso muerto, si tu espalda no est\u00e1 muy fatigada de antemano.<\/p>\n\n\n\n<p>Si hacemos el peso muerto desde el piso en vez de las rodillas, debemos mover nuestras caderas m\u00e1s hacia atr\u00e1s y nuestra espalda queda en una posici\u00f3n m\u00e1s horizontal, as\u00ed:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"744\" src=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazos-de-momento-remo-con-barra-rodillas-vs-piso-1024x744.jpg\" alt=\"Ilustraci\u00f3n de la demanda a la cadera y a la columna en un remo con barra.\" class=\"wp-image-6389\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazos-de-momento-remo-con-barra-rodillas-vs-piso-1024x744.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazos-de-momento-remo-con-barra-rodillas-vs-piso-300x218.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazos-de-momento-remo-con-barra-rodillas-vs-piso-768x558.jpg 768w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/brazos-de-momento-remo-con-barra-rodillas-vs-piso.jpg 1260w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Una espalda m\u00e1s horizontal pone m\u00e1s \u00e9nfasis sobre las caderas y los erectores de la columna.<\/figcaption><\/figure>\n\n\n\n<p>Lo que podemos ver es que los remos desde las rodillas son m\u00e1s f\u00e1ciles para las caderas y los erectores. Como resultado, es m\u00e1s probable que nuestros dorsales o antebrazos sean el factor limitante, por lo cual van a obtener un mayor est\u00edmulo de crecimiento. Al hacer el remo desde el piso, el levantamiento es alrededor de 30% m\u00e1s dif\u00edcil para nuestras caderas y erectores de la columna, por lo cual es mucho m\u00e1s probable que estos limiten nuestro rendimiento, y por tanto, obtengan un mayor crecimiento.<\/p>\n\n\n\n<p>El efecto exacto var\u00eda de persona a persona, pero hacer remos desde las rodillas pone m\u00e1s \u00e9nfasis sobre los dorsales y la espalda superior, mientras que hacerlos desde el piso pone un mayor \u00e9nfasis sobre la espalda inferior.<\/p>\n\n\n\n<p>Esto nos lleva a las variaciones de remo m\u00e1s avanzadas:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"713\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-remo-pendlay.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un remo con barra Pendlay.\" class=\"wp-image-6219\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-remo-pendlay.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-remo-pendlay-300x170.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-remo-pendlay-1024x579.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-remo-pendlay-768x435.jpg 768w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-remo-pendlay-320x180.jpg 320w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<p><strong>El remo Pendlay <\/strong>inicia con la barra en el piso y termina cuando la barra toca el torso. No hay impulso de las caderas, por lo cual las caderas terminan en la misma posici\u00f3n inicial y el \u00e1ngulo de la espalda no cambia. Este es un excelente levantamiento para el crecimiento de los erectores de la columna, pero no debes excederte con \u00e9l. Al hacer una gran cantidad de trabajo con levantamientos con barra pesados, es f\u00e1cil trabajar a los erectores de la columna en exceso.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1260\" height=\"839\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-remo-de-potencia.jpg\" alt=\"Ilustraci\u00f3n de un hombre haciendo un remo de potencia.\" class=\"wp-image-6391\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-remo-de-potencia.jpg 1260w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-remo-de-potencia-300x200.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-remo-de-potencia-1024x682.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2021\/02\/ilustracion-remo-de-potencia-768x511.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n\n\n\n<p><strong>El remo de potencia<\/strong> es como un remo Pendlay pero con impulso de las caderas. El beneficio obvio es que vas a trabajar a los gl\u00fateos y a los isquiosurales m\u00e1s que en el remo Pendlay. El beneficio m\u00e1s s\u00fatil es que tambi\u00e9n vas a obtener \u00edmpetu en la parte baja del levantamiento. Ese \u00edmpetu va a ayudar a los dorsales a sobrepasar el punto de mayor dificultad en la parte alta del movimiento. Esto significa que vas a poder utilizar m\u00e1s peso o hacer m\u00e1s repeticiones, lo cual le dar\u00e1 a tu espalda superior una estimulaci\u00f3n a\u00fan mayor.<\/p>\n\n\n\n<p>Esta variaci\u00f3n de remo tiene la mayor transferencia al peso muerto, y es una de las favoritas entre los levantadores de potencia de alto nivel (como Cailer Woolam). La descentaja es que es un levantamiento grande\u2014en especial si lo que quremos es que sea un accesorio. Nuevamente, tienes que asegurarte de que tu espalda sea suficientemente resistente para soportar lo que demandes de ella.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"30-puentes-de-gl%C3%BAteos-empujes-de-cadera\">Puentes de Gl\u00fateos \/ Empujes de Cadera<\/h3>\n\n\n\n<p><strong>Los puentes de gl\u00fateos y los empujes de cadera son excelentes para el crecimiento de las caderas sin poner mayor estr\u00e9s adicional sobre la espalda o las manos. <\/strong>Son m\u00e1s dif\u00edciles en la posici\u00f3n de finalizaci\u00f3n, por lo cual son especialmente buenos para mejorar la fuerza de finalizaci\u00f3n, pero el m\u00fasculo que ganes va a mejorar la fuerza de tus caderas en cada parte del peso muerto.<\/p>\n\n\n\n<p>Los puentes de gl\u00fateos utilizan un menor rango de movimiento pero no requieren de un ajuste previo complicado y pueden ser cargados con m\u00e1s peso. Son un buen levantamiento para empezar.<\/p>\n\n\n\n<p>Los empujes de cadera requieren de m\u00e1s ajustes previos, pero utilizan un rango de movimiento mucho mayor, por lo cual, t\u00e9cnicamente, son mejores para estimular a los gl\u00fateos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"31-elevaciones-de-espalda-hiperextensiones-invertidas\">Elevaciones de Espalda\/ Hiperextensiones Invertidas<\/h3>\n\n\n\n<p>Si quieres mejorar la fuerza de extensi\u00f3n de tu espalda, estos son los levantamientos ideales. Estos van a fortalecer a los erectores de la columna al tiempo que entrenan a tus caderas. La \u00fanica desventaja es que necesitas una m\u00e1quina especial para hacerlos, lo cual nos lleva a&#8230;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"32-buenos-d%C3%ADas-good-mornings-\">Buenos D\u00edas (<i>Good Mornings<\/i> )<\/h3>\n\n\n\n<p>Los buenos d\u00edas fueron llamados de esa forma debido a que se parecen al movimiento que hacemos al levantarnos de la cama en la ma\u00f1ana. Otra fuente afirma que se debe a que se parecen al movimiento utilizado para desearle un buen d\u00eda a otra persona. Pero&#8230; no hablemos del nombre.<\/p>\n\n\n\n<p><strong>Si quieres una soluci\u00f3n simple para los problemas de espalda en el peso muerto, los buenos d\u00edas son ideales. <\/strong>Son excelentes para fortalecer a los erectores de la columna, los isquiosurales y para mejorar la fuerza de extensi\u00f3n de la espalda. Lo mejor de todo es que no se requiere de ning\u00fan equipo especial, no requieren de un ajuste previo complicado, son f\u00e1ciles de aprender y la recuperaci\u00f3n es r\u00e1pida.<\/p>\n\n\n\n<p>Si entrenas en casa con una barra, los buenos d\u00edas son una buena alternativa a las hiperextensiones invertidas, las elevaciones (extensiones) de espalda e incluso a los <em>glute-ham raises<\/em>. <\/p>\n\n\n\n<p><strong>Barra baja vs. barra alta: <\/strong>as\u00ed como las sentadillas traseras, los buenos d\u00edas pueden hacerse con una posici\u00f3n con barra baja o barra alta. La posici\u00f3n con barra baja es m\u00e1s f\u00e1cil para la espalda y permite utilizar m\u00e1s peso, por lo cual es buena para entrenar la extensi\u00f3n de espalda cuando tu espalda est\u00e1 fatigada. La posici\u00f3n con barra alta es m\u00e1s dif\u00edcil para la espalda pero se hace con menos peso, por lo cual es excelente para mejorar la fuerza de la espalda.<\/p>\n\n\n\n<p><strong>Seguridad: <\/strong>si ya sabes c\u00f3mo hacer una sentadilla y un peso muerto, los buenos d\u00edas no deber\u00edan ser muy peligrosos. En todo caso, es una buena idea utilizar las barras de seguridad (como al hacer sentadillas), y este no es un ejercicio que quieras llegar hasta el fallo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"33-puntos-clave\">Puntos Clave<\/h2>\n\n\n\n<p>El peso muerto es, posiblemente el mejor levantamiento para ganar m\u00fasculo, fuerza y mejorar la apariencia, y tambi\u00e9n nos puede ayudar a vivir una vida m\u00e1s larga y saludable. Pero, a pesar de que es excelente, y a pesar de que sea tan eficiente por serie, tambi\u00e9n genera una incre\u00edble cantidad de fatiga. Por esto, debemos programarlo con menos frecuencia. Menos es m\u00e1s.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1400\" height=\"909\" src=\"http:\/\/outlift.com\/wp-content\/uploads\/2020\/03\/outlift-flaming-biceps-flex-1.jpg\" alt=\"Ilustraci\u00f3n de un hombre con b\u00edceps flexionados y en llamas.\" class=\"wp-image-1499\" srcset=\"https:\/\/outlift.com\/wp-content\/uploads\/2020\/03\/outlift-flaming-biceps-flex-1.jpg 1400w, https:\/\/outlift.com\/wp-content\/uploads\/2020\/03\/outlift-flaming-biceps-flex-1-300x195.jpg 300w, https:\/\/outlift.com\/wp-content\/uploads\/2020\/03\/outlift-flaming-biceps-flex-1-1024x665.jpg 1024w, https:\/\/outlift.com\/wp-content\/uploads\/2020\/03\/outlift-flaming-biceps-flex-1-768x499.jpg 768w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/><\/figure>\n\n\n\n<p>Con un enfoque de menor volumen del peso muerto, es \u00fatil incluir varios levantamientos de asistencia y accesorios. Con estos podemos aumentar el volumen y la frecuencia para acercarlos al rango ideal, pero sin acumular tanta fatiga. Adem\u00e1s, tambi\u00e9n permite que nuestra columna se recupere completamente entre las sesiones pesadas de peso muerto.<\/p>\n\n\n\n<p>De los levantamientos de asistencia, el peso muerto rumano es, posiblemente, la mejor opci\u00f3n. Si te genera mucha fatiga en la espalda inferior o en el agarre, intenta hacerlo con una pierna a la vez.<\/p>\n\n\n\n<p>De los levantamientos accesorios, nada supera al remo con barra. Pero, si son demasiado para manejar la fatiga de entrenamiento, las extensiones de espalda o los buenos d\u00edas son una forma sencilla de fortalecer a los erectores de la columna sin acumular tanta fatiga adicional.<\/p>\n\n\n\n<p>Finalmente, progresar en el peso muerto podr\u00eda ser m\u00e1s f\u00e1cil si incluyes sentadillas cargadas frontalmente en tu programa, como las sentadillas frontales y las sentadillas Zercher.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El peso muerto fortalece a nuestro cuerpo desde los dedos de las manos hasta los dedos de los pies, estimulando a una gran cantidad de m\u00fasculos del cuerpo, desde los antebrazos hasta las pantorillas. De hecho, es tan buen indicador de la fuerza general que es el \u00fanico levantamiento fundamental tanto en el levantamiento de&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[96,70,57],"tags":[84,85],"class_list":["post-2629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espanol","category-los-cinco-grandes-levantamientos","category-musculacion","tag-big-5-lifts-es","tag-deadlift-es"],"featured_image_src":"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/sumo-deadlift-illustration.jpg","author_info":{"display_name":"Shane Duquette","author_link":"#molongui-disabled-link"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Peso Muerto (Gu\u00eda para Tama\u00f1o &amp; Est\u00e9tica) &#8211; Outlift<\/title>\n<meta name=\"description\" content=\"The deadlift is the only lift that&#039;s a staple of both powerlifting and strongman training. But what if you&#039;re trying to deadlift for muscle size?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Peso Muerto (Gu\u00eda para Tama\u00f1o &amp; Est\u00e9tica) &#8211; Outlift\" \/>\n<meta property=\"og:description\" content=\"The deadlift is the only lift that&#039;s a staple of both powerlifting and strongman training. But what if you&#039;re trying to deadlift for muscle size?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/\" \/>\n<meta property=\"og:site_name\" content=\"Outlift\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/williamshane\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-30T20:50:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-20T22:47:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/sumo-deadlift-illustration.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"798\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Shane Duquette\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Shane Duquette\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"59 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/peso-muerto-guia-para-ganar-musculo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/peso-muerto-guia-para-ganar-musculo\\\/\"},\"author\":{\"name\":\"Shane Duquette\",\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/#\\\/schema\\\/person\\\/58497e92557754fe4d7bfe4c18916c7e\"},\"headline\":\"El Peso Muerto (Gu\u00eda para Tama\u00f1o &#038; Est\u00e9tica)\",\"datePublished\":\"2019-08-30T20:50:34+00:00\",\"dateModified\":\"2021-02-20T22:47:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/peso-muerto-guia-para-ganar-musculo\\\/\"},\"wordCount\":13018,\"commentCount\":4,\"image\":{\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/peso-muerto-guia-para-ganar-musculo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/outlift.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/sumo-deadlift-illustration.jpg\",\"keywords\":[\"big 5 lifts\",\"deadlift\"],\"articleSection\":[\"Espa\u00f1ol\",\"Los Cinco Grandes Levantamientos\",\"Musculaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/outlift.com\\\/es\\\/peso-muerto-guia-para-ganar-musculo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/peso-muerto-guia-para-ganar-musculo\\\/\",\"url\":\"https:\\\/\\\/outlift.com\\\/es\\\/peso-muerto-guia-para-ganar-musculo\\\/\",\"name\":\"El Peso Muerto (Gu\u00eda para Tama\u00f1o & Est\u00e9tica) &#8211; Outlift\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/peso-muerto-guia-para-ganar-musculo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/peso-muerto-guia-para-ganar-musculo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/outlift.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/sumo-deadlift-illustration.jpg\",\"datePublished\":\"2019-08-30T20:50:34+00:00\",\"dateModified\":\"2021-02-20T22:47:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/#\\\/schema\\\/person\\\/58497e92557754fe4d7bfe4c18916c7e\"},\"description\":\"The deadlift is the only lift that's a staple of both powerlifting and strongman training. But what if you're trying to deadlift for muscle size?\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/outlift.com\\\/es\\\/peso-muerto-guia-para-ganar-musculo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/peso-muerto-guia-para-ganar-musculo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/outlift.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/sumo-deadlift-illustration.jpg\",\"contentUrl\":\"https:\\\/\\\/outlift.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/sumo-deadlift-illustration.jpg\",\"width\":1400,\"height\":798},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/outlift.com\\\/es\\\/\",\"name\":\"Outlift\",\"description\":\"M\u00fasculos, Fuerza, Salud y Est\u00e9tica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/outlift.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},[{\"@type\":[\"Person\"],\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/#\\\/schema\\\/person\\\/58497e92557754fe4d7bfe4c18916c7e\",\"name\":\"Shane Duquette\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ac7be55af703e5388c58051d37f493b3090de0a7339eb87679a8c1ac18a1825?s=96&d=retro&r=g\",\"inLanguage\":\"es_ES\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ac7be55af703e5388c58051d37f493b3090de0a7339eb87679a8c1ac18a1825?s=96&d=retro&r=g\",\"caption\":\"Shane Duquette\"}},{\"@type\":[\"Person\"],\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/#\\\/schema\\\/person\\\/58497e92557754fe4d7bfe4c18916c7e\",\"name\":\"Marco Walker-Ng, BHSc, PTS\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ac7be55af703e5388c58051d37f493b3090de0a7339eb87679a8c1ac18a1825?s=96&d=retro&r=g\",\"inLanguage\":\"es_ES\",\"url\":\"https:\\\/\\\/outlift.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/marco-walker-ng-strength-coach-personal-trainer-300x300-1.jpg\",\"caption\":\"Marco Walker-Ng, BHSc, PTS\"}},{\"@type\":[\"Person\"],\"@id\":\"https:\\\/\\\/outlift.com\\\/es\\\/#\\\/schema\\\/person\\\/58497e92557754fe4d7bfe4c18916c7e\",\"name\":\"Camilo J. P\u00e9rez Espinosa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ac7be55af703e5388c58051d37f493b3090de0a7339eb87679a8c1ac18a1825?s=96&d=retro&r=g\",\"inLanguage\":\"es_ES\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9d15ca2af4b46281fb1faa8bc474fa6ad2c20f6a582eca09fed5db50e4c864?s=96&d=retro&r=g\",\"caption\":\"Camilo J. P\u00e9rez Espinosa\"}}]]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Peso Muerto (Gu\u00eda para Tama\u00f1o & Est\u00e9tica) &#8211; Outlift","description":"The deadlift is the only lift that's a staple of both powerlifting and strongman training. But what if you're trying to deadlift for muscle size?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/","og_locale":"es_ES","og_type":"article","og_title":"El Peso Muerto (Gu\u00eda para Tama\u00f1o & Est\u00e9tica) &#8211; Outlift","og_description":"The deadlift is the only lift that's a staple of both powerlifting and strongman training. But what if you're trying to deadlift for muscle size?","og_url":"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/","og_site_name":"Outlift","article_author":"https:\/\/www.facebook.com\/williamshane","article_published_time":"2019-08-30T20:50:34+00:00","article_modified_time":"2021-02-20T22:47:24+00:00","og_image":[{"width":1400,"height":798,"url":"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/sumo-deadlift-illustration.jpg","type":"image\/jpeg"}],"author":"Shane Duquette","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Shane Duquette","Tiempo de lectura":"59 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#article","isPartOf":{"@id":"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/"},"author":{"name":"Shane Duquette","@id":"https:\/\/outlift.com\/es\/#\/schema\/person\/58497e92557754fe4d7bfe4c18916c7e"},"headline":"El Peso Muerto (Gu\u00eda para Tama\u00f1o &#038; Est\u00e9tica)","datePublished":"2019-08-30T20:50:34+00:00","dateModified":"2021-02-20T22:47:24+00:00","mainEntityOfPage":{"@id":"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/"},"wordCount":13018,"commentCount":4,"image":{"@id":"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#primaryimage"},"thumbnailUrl":"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/sumo-deadlift-illustration.jpg","keywords":["big 5 lifts","deadlift"],"articleSection":["Espa\u00f1ol","Los Cinco Grandes Levantamientos","Musculaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/","url":"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/","name":"El Peso Muerto (Gu\u00eda para Tama\u00f1o & Est\u00e9tica) &#8211; Outlift","isPartOf":{"@id":"https:\/\/outlift.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#primaryimage"},"image":{"@id":"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#primaryimage"},"thumbnailUrl":"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/sumo-deadlift-illustration.jpg","datePublished":"2019-08-30T20:50:34+00:00","dateModified":"2021-02-20T22:47:24+00:00","author":{"@id":"https:\/\/outlift.com\/es\/#\/schema\/person\/58497e92557754fe4d7bfe4c18916c7e"},"description":"The deadlift is the only lift that's a staple of both powerlifting and strongman training. But what if you're trying to deadlift for muscle size?","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/outlift.com\/es\/peso-muerto-guia-para-ganar-musculo\/#primaryimage","url":"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/sumo-deadlift-illustration.jpg","contentUrl":"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/sumo-deadlift-illustration.jpg","width":1400,"height":798},{"@type":"WebSite","@id":"https:\/\/outlift.com\/es\/#website","url":"https:\/\/outlift.com\/es\/","name":"Outlift","description":"M\u00fasculos, Fuerza, Salud y Est\u00e9tica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/outlift.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},[{"@type":["Person"],"@id":"https:\/\/outlift.com\/es\/#\/schema\/person\/58497e92557754fe4d7bfe4c18916c7e","name":"Shane Duquette","image":{"@type":"ImageObject","@id":"https:\/\/secure.gravatar.com\/avatar\/0ac7be55af703e5388c58051d37f493b3090de0a7339eb87679a8c1ac18a1825?s=96&d=retro&r=g","inLanguage":"es_ES","url":"https:\/\/secure.gravatar.com\/avatar\/0ac7be55af703e5388c58051d37f493b3090de0a7339eb87679a8c1ac18a1825?s=96&d=retro&r=g","caption":"Shane Duquette"}},{"@type":["Person"],"@id":"https:\/\/outlift.com\/es\/#\/schema\/person\/58497e92557754fe4d7bfe4c18916c7e","name":"Marco Walker-Ng, BHSc, PTS","image":{"@type":"ImageObject","@id":"https:\/\/secure.gravatar.com\/avatar\/0ac7be55af703e5388c58051d37f493b3090de0a7339eb87679a8c1ac18a1825?s=96&d=retro&r=g","inLanguage":"es_ES","url":"https:\/\/outlift.com\/wp-content\/uploads\/2021\/10\/marco-walker-ng-strength-coach-personal-trainer-300x300-1.jpg","caption":"Marco Walker-Ng, BHSc, PTS"}},{"@type":["Person"],"@id":"https:\/\/outlift.com\/es\/#\/schema\/person\/58497e92557754fe4d7bfe4c18916c7e","name":"Camilo J. P\u00e9rez Espinosa","image":{"@type":"ImageObject","@id":"https:\/\/secure.gravatar.com\/avatar\/0ac7be55af703e5388c58051d37f493b3090de0a7339eb87679a8c1ac18a1825?s=96&d=retro&r=g","inLanguage":"es_ES","url":"https:\/\/secure.gravatar.com\/avatar\/ff9d15ca2af4b46281fb1faa8bc474fa6ad2c20f6a582eca09fed5db50e4c864?s=96&d=retro&r=g","caption":"Camilo J. P\u00e9rez Espinosa"}}]]}},"jetpack_featured_media_url":"https:\/\/outlift.com\/wp-content\/uploads\/2019\/08\/sumo-deadlift-illustration.jpg","jetpack_shortlink":"https:\/\/wp.me\/paBMwO-Gp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/outlift.com\/es\/wp-json\/wp\/v2\/posts\/2629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/outlift.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/outlift.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/outlift.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/outlift.com\/es\/wp-json\/wp\/v2\/comments?post=2629"}],"version-history":[{"count":53,"href":"https:\/\/outlift.com\/es\/wp-json\/wp\/v2\/posts\/2629\/revisions"}],"predecessor-version":[{"id":6394,"href":"https:\/\/outlift.com\/es\/wp-json\/wp\/v2\/posts\/2629\/revisions\/6394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/outlift.com\/es\/wp-json\/wp\/v2\/media\/1389"}],"wp:attachment":[{"href":"https:\/\/outlift.com\/es\/wp-json\/wp\/v2\/media?parent=2629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/outlift.com\/es\/wp-json\/wp\/v2\/categories?post=2629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/outlift.com\/es\/wp-json\/wp\/v2\/tags?post=2629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}